{"id":22,"date":"2024-06-21T15:54:26","date_gmt":"2024-06-21T18:54:26","guid":{"rendered":"https:\/\/lemos.letsite.com.br\/?page_id=22"},"modified":"2024-09-23T16:46:56","modified_gmt":"2024-09-23T19:46:56","slug":"contato","status":"publish","type":"page","link":"https:\/\/lemosadv.com.br\/en\/contato\/","title":{"rendered":"Contact"},"content":{"rendered":"<p><\/p>\n<h2>Contact Us<\/h2>\n<p>If you have any questions, suggestions, or complaints, simply fill out the fields below and send us a message. Lemos will make every effort to respond as soon as possible and address your request.<\/p>","protected":false},"excerpt":{"rendered":"<p>Rua A\u00e7u, 28<br \/>\nAlphaville Empresarial<br \/>\nCampinas-SP<br \/>\nCEP: 13.098-335<\/p>\n","protected":false},"author":1,"featured_media":235,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-contato.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-22","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fale com o Lemos - Advocacia Para Neg\u00f3cios<\/title>\n<meta name=\"description\" content=\"Com uma equipe altamente qualificada e a participa\u00e7\u00e3o ativa de suas principais lideran\u00e7as, o Lemos se destaca pela excel\u00eancia jur\u00eddica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lemosadv.com.br\/contato\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fale com o Lemos - Advocacia Para Neg\u00f3cios\" \/>\n<meta property=\"og:description\" content=\"Com uma equipe altamente qualificada e a participa\u00e7\u00e3o ativa de suas principais lideran\u00e7as, o Lemos se destaca pela excel\u00eancia jur\u00eddica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lemosadv.com.br\/contato\/\" \/>\n<meta property=\"og:site_name\" content=\"Lemos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-23T19:46:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/ctt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/contato\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/contato\\\/\",\"name\":\"Fale com o Lemos - Advocacia Para Neg\u00f3cios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/contato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/contato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ctt.jpg\",\"datePublished\":\"2024-06-21T18:54:26+00:00\",\"dateModified\":\"2024-09-23T19:46:56+00:00\",\"description\":\"Com uma equipe altamente qualificada e a participa\u00e7\u00e3o ativa de suas principais lideran\u00e7as, o Lemos se destaca pela excel\u00eancia jur\u00eddica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/contato\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lemosadv.com.br\\\/contato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/contato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ctt.jpg\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ctt.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/contato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"name\":\"Lemos \u2013 Advocacia para Neg\u00f3cios\",\"description\":\"Escrit\u00f3rio de Advocacia\",\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"alternateName\":\"Lemos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\",\"name\":\"Lemos - Advocacia para neg\u00f3cios\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Lemos - Advocacia para neg\u00f3cios\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/lemosadvocaciaparanegocios\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lemosadv_\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lemosadvocacia\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fale com o Lemos - Advocacia Para Neg\u00f3cios","description":"Com uma equipe altamente qualificada e a participa\u00e7\u00e3o ativa de suas principais lideran\u00e7as, o Lemos se destaca pela excel\u00eancia jur\u00eddica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lemosadv.com.br\/contato\/","og_locale":"en_US","og_type":"article","og_title":"Fale com o Lemos - Advocacia Para Neg\u00f3cios","og_description":"Com uma equipe altamente qualificada e a participa\u00e7\u00e3o ativa de suas principais lideran\u00e7as, o Lemos se destaca pela excel\u00eancia jur\u00eddica.","og_url":"https:\/\/lemosadv.com.br\/contato\/","og_site_name":"Lemos","article_publisher":"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","article_modified_time":"2024-09-23T19:46:56+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/ctt.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lemosadv.com.br\/contato\/","url":"https:\/\/lemosadv.com.br\/contato\/","name":"Fale com o Lemos - Advocacia Para Neg\u00f3cios","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/pb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lemosadv.com.br\/contato\/#primaryimage"},"image":{"@id":"https:\/\/lemosadv.com.br\/contato\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/ctt.jpg","datePublished":"2024-06-21T18:54:26+00:00","dateModified":"2024-09-23T19:46:56+00:00","description":"Com uma equipe altamente qualificada e a participa\u00e7\u00e3o ativa de suas principais lideran\u00e7as, o Lemos se destaca pela excel\u00eancia jur\u00eddica.","breadcrumb":{"@id":"https:\/\/lemosadv.com.br\/contato\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lemosadv.com.br\/contato\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lemosadv.com.br\/contato\/#primaryimage","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/ctt.jpg","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/ctt.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/lemosadv.com.br\/contato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lemosadv.com.br\/pb\/"},{"@type":"ListItem","position":2,"name":"Contato"}]},{"@type":"WebSite","@id":"https:\/\/lemosadv.com.br\/pb\/#website","url":"https:\/\/lemosadv.com.br\/pb\/","name":"Lemos \u2013 Advocacia para Neg\u00f3cios","description":"Escrit\u00f3rio de Advocacia","publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"alternateName":"Lemos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lemosadv.com.br\/pb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lemosadv.com.br\/pb\/#organization","name":"Lemos - Advocacia para neg\u00f3cios","url":"https:\/\/lemosadv.com.br\/pb\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","width":512,"height":512,"caption":"Lemos - Advocacia para neg\u00f3cios"},"image":{"@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","https:\/\/www.instagram.com\/lemosadv_\/","https:\/\/www.linkedin.com\/company\/lemosadvocacia"]}]}},"_links":{"self":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/pages\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/comments?post=22"}],"version-history":[{"count":5,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/pages\/22\/revisions"}],"predecessor-version":[{"id":454,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/pages\/22\/revisions\/454"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/media\/235"}],"wp:attachment":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/media?parent=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}