{"id":2085,"date":"2026-03-17T16:14:59","date_gmt":"2026-03-17T19:14:59","guid":{"rendered":"https:\/\/lemosadv.com.br\/?p=2085"},"modified":"2026-03-17T18:31:18","modified_gmt":"2026-03-17T21:31:18","slug":"proteca-digital-para-criancas-e-adolescentes","status":"publish","type":"post","link":"https:\/\/lemosadv.com.br\/en\/proteca-digital-para-criancas-e-adolescentes\/","title":{"rendered":"(pt) ECA Digital entra em vigor e imp\u00f5e novas obriga\u00e7\u00f5es para prote\u00e7\u00e3o de crian\u00e7as e adolescentes no ambiente on-line"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/2085\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pb\" title=\"pt\">pt<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in pt.<\/p>\n","protected":false},"author":2,"featured_media":2087,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[35],"class_list":["post-2085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","tag-direito-digital"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"description\" content=\"As obriga\u00e7\u00f5es incluem mecanismos de aferi\u00e7\u00e3o de idade, ferramentas de supervis\u00e3o, ado\u00e7\u00e3o de medidas de seguran\u00e7a e de prote\u00e7\u00e3o e mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lemosadv.com.br\/proteca-digital-para-criancas-e-adolescentes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:pb]ECA Digital entra em vigor e imp\u00f5e novas obriga\u00e7\u00f5es para prote\u00e7\u00e3o de crian\u00e7as e adolescentes no ambiente on-line[:] &#8211; Lemos\" \/>\n<meta property=\"og:description\" content=\"As obriga\u00e7\u00f5es incluem mecanismos de aferi\u00e7\u00e3o de idade, ferramentas de supervis\u00e3o, ado\u00e7\u00e3o de medidas de seguran\u00e7a e de prote\u00e7\u00e3o e mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lemosadv.com.br\/proteca-digital-para-criancas-e-adolescentes\/\" \/>\n<meta property=\"og:site_name\" content=\"Lemos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-17T19:14:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-17T21:31:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/Captura-de-Tela-2026-03-17-as-16.20.37-1024x682.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ana Paula Perez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Paula Perez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/proteca-digital-para-criancas-e-adolescentes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/proteca-digital-para-criancas-e-adolescentes\\\/\"},\"author\":{\"name\":\"Ana Paula Perez\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/9d4d106f4f03dbaa7164e5abe5b03894\"},\"headline\":\"(pt) ECA Digital entra em vigor e imp\u00f5e novas obriga\u00e7\u00f5es para prote\u00e7\u00e3o de crian\u00e7as e adolescentes no ambiente on-line\",\"datePublished\":\"2026-03-17T19:14:59+00:00\",\"dateModified\":\"2026-03-17T21:31:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/proteca-digital-para-criancas-e-adolescentes\\\/\"},\"wordCount\":525,\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/proteca-digital-para-criancas-e-adolescentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Captura-de-Tela-2026-03-17-as-16.20.37.png\",\"keywords\":[\"Digital Law\"],\"articleSection\":[\"Artigos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/proteca-digital-para-criancas-e-adolescentes\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/proteca-digital-para-criancas-e-adolescentes\\\/\",\"name\":\"[:pb]ECA Digital entra em vigor e imp\u00f5e novas obriga\u00e7\u00f5es para prote\u00e7\u00e3o de crian\u00e7as e adolescentes no ambiente on-line[:] &#8211; Lemos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/proteca-digital-para-criancas-e-adolescentes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/proteca-digital-para-criancas-e-adolescentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Captura-de-Tela-2026-03-17-as-16.20.37.png\",\"datePublished\":\"2026-03-17T19:14:59+00:00\",\"dateModified\":\"2026-03-17T21:31:18+00:00\",\"description\":\"As obriga\u00e7\u00f5es incluem mecanismos de aferi\u00e7\u00e3o de idade, ferramentas de supervis\u00e3o, ado\u00e7\u00e3o de medidas de seguran\u00e7a e de prote\u00e7\u00e3o e mais.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/proteca-digital-para-criancas-e-adolescentes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lemosadv.com.br\\\/proteca-digital-para-criancas-e-adolescentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/proteca-digital-para-criancas-e-adolescentes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Captura-de-Tela-2026-03-17-as-16.20.37.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Captura-de-Tela-2026-03-17-as-16.20.37.png\",\"width\":2022,\"height\":1346},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/proteca-digital-para-criancas-e-adolescentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ECA Digital entra em vigor e imp\u00f5e novas obriga\u00e7\u00f5es para prote\u00e7\u00e3o de crian\u00e7as e adolescentes no ambiente on-line\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"name\":\"Lemos \u2013 Advocacia para Neg\u00f3cios\",\"description\":\"Escrit\u00f3rio de Advocacia\",\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"alternateName\":\"Lemos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\",\"name\":\"Lemos - Advocacia para neg\u00f3cios\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Lemos - Advocacia para neg\u00f3cios\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/lemosadvocaciaparanegocios\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lemosadv_\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lemosadvocacia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/9d4d106f4f03dbaa7164e5abe5b03894\",\"name\":\"Ana Paula Perez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g\",\"caption\":\"Ana Paula Perez\"},\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/en\\\/author\\\/lemos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:pb]ECA Digital entra em vigor e imp\u00f5e novas obriga\u00e7\u00f5es para prote\u00e7\u00e3o de crian\u00e7as e adolescentes no ambiente on-line[:] &#8211; Lemos","description":"As obriga\u00e7\u00f5es incluem mecanismos de aferi\u00e7\u00e3o de idade, ferramentas de supervis\u00e3o, ado\u00e7\u00e3o de medidas de seguran\u00e7a e de prote\u00e7\u00e3o e mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lemosadv.com.br\/proteca-digital-para-criancas-e-adolescentes\/","og_locale":"en_US","og_type":"article","og_title":"[:pb]ECA Digital entra em vigor e imp\u00f5e novas obriga\u00e7\u00f5es para prote\u00e7\u00e3o de crian\u00e7as e adolescentes no ambiente on-line[:] &#8211; Lemos","og_description":"As obriga\u00e7\u00f5es incluem mecanismos de aferi\u00e7\u00e3o de idade, ferramentas de supervis\u00e3o, ado\u00e7\u00e3o de medidas de seguran\u00e7a e de prote\u00e7\u00e3o e mais.","og_url":"https:\/\/lemosadv.com.br\/proteca-digital-para-criancas-e-adolescentes\/","og_site_name":"Lemos","article_publisher":"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","article_published_time":"2026-03-17T19:14:59+00:00","article_modified_time":"2026-03-17T21:31:18+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/Captura-de-Tela-2026-03-17-as-16.20.37-1024x682.png","type":"image\/png"}],"author":"Ana Paula Perez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ana Paula Perez","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lemosadv.com.br\/proteca-digital-para-criancas-e-adolescentes\/#article","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/proteca-digital-para-criancas-e-adolescentes\/"},"author":{"name":"Ana Paula Perez","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/9d4d106f4f03dbaa7164e5abe5b03894"},"headline":"(pt) ECA Digital entra em vigor e imp\u00f5e novas obriga\u00e7\u00f5es para prote\u00e7\u00e3o de crian\u00e7as e adolescentes no ambiente on-line","datePublished":"2026-03-17T19:14:59+00:00","dateModified":"2026-03-17T21:31:18+00:00","mainEntityOfPage":{"@id":"https:\/\/lemosadv.com.br\/proteca-digital-para-criancas-e-adolescentes\/"},"wordCount":525,"publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"image":{"@id":"https:\/\/lemosadv.com.br\/proteca-digital-para-criancas-e-adolescentes\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/Captura-de-Tela-2026-03-17-as-16.20.37.png","keywords":["Digital Law"],"articleSection":["Artigos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/lemosadv.com.br\/proteca-digital-para-criancas-e-adolescentes\/","url":"https:\/\/lemosadv.com.br\/proteca-digital-para-criancas-e-adolescentes\/","name":"[:pb]ECA Digital entra em vigor e imp\u00f5e novas obriga\u00e7\u00f5es para prote\u00e7\u00e3o de crian\u00e7as e adolescentes no ambiente on-line[:] &#8211; Lemos","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/pb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lemosadv.com.br\/proteca-digital-para-criancas-e-adolescentes\/#primaryimage"},"image":{"@id":"https:\/\/lemosadv.com.br\/proteca-digital-para-criancas-e-adolescentes\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/Captura-de-Tela-2026-03-17-as-16.20.37.png","datePublished":"2026-03-17T19:14:59+00:00","dateModified":"2026-03-17T21:31:18+00:00","description":"As obriga\u00e7\u00f5es incluem mecanismos de aferi\u00e7\u00e3o de idade, ferramentas de supervis\u00e3o, ado\u00e7\u00e3o de medidas de seguran\u00e7a e de prote\u00e7\u00e3o e mais.","breadcrumb":{"@id":"https:\/\/lemosadv.com.br\/proteca-digital-para-criancas-e-adolescentes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lemosadv.com.br\/proteca-digital-para-criancas-e-adolescentes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lemosadv.com.br\/proteca-digital-para-criancas-e-adolescentes\/#primaryimage","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/Captura-de-Tela-2026-03-17-as-16.20.37.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/Captura-de-Tela-2026-03-17-as-16.20.37.png","width":2022,"height":1346},{"@type":"BreadcrumbList","@id":"https:\/\/lemosadv.com.br\/proteca-digital-para-criancas-e-adolescentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lemosadv.com.br\/pb\/"},{"@type":"ListItem","position":2,"name":"ECA Digital entra em vigor e imp\u00f5e novas obriga\u00e7\u00f5es para prote\u00e7\u00e3o de crian\u00e7as e adolescentes no ambiente on-line"}]},{"@type":"WebSite","@id":"https:\/\/lemosadv.com.br\/pb\/#website","url":"https:\/\/lemosadv.com.br\/pb\/","name":"Lemos \u2013 Advocacia para Neg\u00f3cios","description":"Escrit\u00f3rio de Advocacia","publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"alternateName":"Lemos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lemosadv.com.br\/pb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lemosadv.com.br\/pb\/#organization","name":"Lemos - Advocacia para neg\u00f3cios","url":"https:\/\/lemosadv.com.br\/pb\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","width":512,"height":512,"caption":"Lemos - Advocacia para neg\u00f3cios"},"image":{"@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","https:\/\/www.instagram.com\/lemosadv_\/","https:\/\/www.linkedin.com\/company\/lemosadvocacia"]},{"@type":"Person","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/9d4d106f4f03dbaa7164e5abe5b03894","name":"Ana Paula Perez","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g","caption":"Ana Paula Perez"},"url":"https:\/\/lemosadv.com.br\/en\/author\/lemos\/"}]}},"_links":{"self":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/posts\/2085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/comments?post=2085"}],"version-history":[{"count":0,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/posts\/2085\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/media\/2087"}],"wp:attachment":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/media?parent=2085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/categories?post=2085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/tags?post=2085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}