{"id":390,"date":"2023-10-26T16:23:54","date_gmt":"2023-10-26T19:23:54","guid":{"rendered":"https:\/\/lemos.letsite.com.br\/?p=390"},"modified":"2024-07-17T16:44:55","modified_gmt":"2024-07-17T19:44:55","slug":"dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades","status":"publish","type":"post","link":"https:\/\/lemosadv.com.br\/en\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\/","title":{"rendered":"(pt) Dados Pessoais Sens\u00edveis e a Comunidade LGBTQ+: Protegendo Identidades"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/390\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pb\" title=\"pt\">pt<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in pt.<\/p>\n","protected":false},"author":1,"featured_media":396,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[35],"class_list":["post-390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","tag-direito-digital"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lemosadv.com.br\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:pb]Dados Pessoais Sens\u00edveis e a Comunidade LGBTQ+: Protegendo Identidades[:] &#8211; Lemos\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in pt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lemosadv.com.br\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\/\" \/>\n<meta property=\"og:site_name\" content=\"Lemos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-26T19:23:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-17T19:44:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2023\/10\/lbgt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"807\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/d596db55770da72ca6d193b9667d8b51\"},\"headline\":\"(pt) Dados Pessoais Sens\u00edveis e a Comunidade LGBTQ+: Protegendo Identidades\",\"datePublished\":\"2023-10-26T19:23:54+00:00\",\"dateModified\":\"2024-07-17T19:44:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\\\/\"},\"wordCount\":544,\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/lbgt.jpg\",\"keywords\":[\"Digital Law\"],\"articleSection\":[\"Artigos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\\\/\",\"name\":\"[:pb]Dados Pessoais Sens\u00edveis e a Comunidade LGBTQ+: Protegendo Identidades[:] &#8211; Lemos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/lbgt.jpg\",\"datePublished\":\"2023-10-26T19:23:54+00:00\",\"dateModified\":\"2024-07-17T19:44:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lemosadv.com.br\\\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/lbgt.jpg\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/lbgt.jpg\",\"width\":807,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dados Pessoais Sens\u00edveis e a Comunidade LGBTQ+: Protegendo Identidades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"name\":\"Lemos \u2013 Advocacia para Neg\u00f3cios\",\"description\":\"Escrit\u00f3rio de Advocacia\",\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"alternateName\":\"Lemos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\",\"name\":\"Lemos - Advocacia para neg\u00f3cios\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Lemos - Advocacia para neg\u00f3cios\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/lemosadvocaciaparanegocios\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lemosadv_\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lemosadvocacia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/d596db55770da72ca6d193b9667d8b51\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/lemos.letsite.com.br\"],\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:pb]Dados Pessoais Sens\u00edveis e a Comunidade LGBTQ+: Protegendo Identidades[:] &#8211; Lemos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lemosadv.com.br\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\/","og_locale":"en_US","og_type":"article","og_title":"[:pb]Dados Pessoais Sens\u00edveis e a Comunidade LGBTQ+: Protegendo Identidades[:] &#8211; Lemos","og_description":"Sorry, this entry is only available in pt.","og_url":"https:\/\/lemosadv.com.br\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\/","og_site_name":"Lemos","article_publisher":"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","article_published_time":"2023-10-26T19:23:54+00:00","article_modified_time":"2024-07-17T19:44:55+00:00","og_image":[{"width":807,"height":480,"url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2023\/10\/lbgt.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lemosadv.com.br\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\/#article","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\/"},"author":{"name":"admin","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/d596db55770da72ca6d193b9667d8b51"},"headline":"(pt) Dados Pessoais Sens\u00edveis e a Comunidade LGBTQ+: Protegendo Identidades","datePublished":"2023-10-26T19:23:54+00:00","dateModified":"2024-07-17T19:44:55+00:00","mainEntityOfPage":{"@id":"https:\/\/lemosadv.com.br\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\/"},"wordCount":544,"publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"image":{"@id":"https:\/\/lemosadv.com.br\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2023\/10\/lbgt.jpg","keywords":["Digital Law"],"articleSection":["Artigos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/lemosadv.com.br\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\/","url":"https:\/\/lemosadv.com.br\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\/","name":"[:pb]Dados Pessoais Sens\u00edveis e a Comunidade LGBTQ+: Protegendo Identidades[:] &#8211; Lemos","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/pb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lemosadv.com.br\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\/#primaryimage"},"image":{"@id":"https:\/\/lemosadv.com.br\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2023\/10\/lbgt.jpg","datePublished":"2023-10-26T19:23:54+00:00","dateModified":"2024-07-17T19:44:55+00:00","breadcrumb":{"@id":"https:\/\/lemosadv.com.br\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lemosadv.com.br\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lemosadv.com.br\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\/#primaryimage","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2023\/10\/lbgt.jpg","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2023\/10\/lbgt.jpg","width":807,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/lemosadv.com.br\/dados-pessoais-sensiveis-e-a-comunidade-lgbtq-protegendo-identidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lemosadv.com.br\/pb\/"},{"@type":"ListItem","position":2,"name":"Dados Pessoais Sens\u00edveis e a Comunidade LGBTQ+: Protegendo Identidades"}]},{"@type":"WebSite","@id":"https:\/\/lemosadv.com.br\/pb\/#website","url":"https:\/\/lemosadv.com.br\/pb\/","name":"Lemos \u2013 Advocacia para Neg\u00f3cios","description":"Escrit\u00f3rio de Advocacia","publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"alternateName":"Lemos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lemosadv.com.br\/pb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lemosadv.com.br\/pb\/#organization","name":"Lemos - Advocacia para neg\u00f3cios","url":"https:\/\/lemosadv.com.br\/pb\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","width":512,"height":512,"caption":"Lemos - Advocacia para neg\u00f3cios"},"image":{"@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","https:\/\/www.instagram.com\/lemosadv_\/","https:\/\/www.linkedin.com\/company\/lemosadvocacia"]},{"@type":"Person","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/d596db55770da72ca6d193b9667d8b51","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/lemos.letsite.com.br"],"url":"https:\/\/lemosadv.com.br\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/posts\/390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/comments?post=390"}],"version-history":[{"count":0,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/posts\/390\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/media\/396"}],"wp:attachment":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/media?parent=390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/categories?post=390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/tags?post=390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}