{"id":752,"date":"2025-04-08T09:48:40","date_gmt":"2025-04-08T12:48:40","guid":{"rendered":"https:\/\/lemosadv.com.br\/?p=752"},"modified":"2026-02-20T15:11:27","modified_gmt":"2026-02-20T18:11:27","slug":"riscos-digitais-vulnerabilidade-mulher","status":"publish","type":"post","link":"https:\/\/lemosadv.com.br\/en\/riscos-digitais-vulnerabilidade-mulher\/","title":{"rendered":"(pt) Podcast: Riscos Digitais e a Vulnerabilidade Cibern\u00e9tica da Mulher"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/752\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pb\" title=\"pt\">pt<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in pt.<\/p>\n","protected":false},"author":2,"featured_media":756,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[43],"tags":[],"class_list":["post-752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcasts"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>vulnerabilidade cibern\u00e9tica mulher<\/title>\n<meta name=\"description\" content=\"Podcast discute vulnerabilidade cibern\u00e9tica da mulher e caminhos jur\u00eddicos para prote\u00e7\u00e3o digital e responsabiliza\u00e7\u00e3o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lemosadv.com.br\/riscos-digitais-vulnerabilidade-mulher\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"vulnerabilidade cibern\u00e9tica mulher\" \/>\n<meta property=\"og:description\" content=\"Podcast discute vulnerabilidade cibern\u00e9tica da mulher e caminhos jur\u00eddicos para prote\u00e7\u00e3o digital e responsabiliza\u00e7\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lemosadv.com.br\/riscos-digitais-vulnerabilidade-mulher\/\" \/>\n<meta property=\"og:site_name\" content=\"Lemos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-08T12:48:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-20T18:11:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2025\/04\/capa-YouTube-FINAL-2-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ana Paula Perez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Paula Perez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/riscos-digitais-vulnerabilidade-mulher\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/riscos-digitais-vulnerabilidade-mulher\\\/\"},\"author\":{\"name\":\"Ana Paula Perez\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/9d4d106f4f03dbaa7164e5abe5b03894\"},\"headline\":\"(pt) Podcast: Riscos Digitais e a Vulnerabilidade Cibern\u00e9tica da Mulher\",\"datePublished\":\"2025-04-08T12:48:40+00:00\",\"dateModified\":\"2026-02-20T18:11:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/riscos-digitais-vulnerabilidade-mulher\\\/\"},\"wordCount\":38,\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/riscos-digitais-vulnerabilidade-mulher\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/capa-YouTube-FINAL-2-1.png\",\"articleSection\":[\"Podcasts\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/riscos-digitais-vulnerabilidade-mulher\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/riscos-digitais-vulnerabilidade-mulher\\\/\",\"name\":\"vulnerabilidade cibern\u00e9tica mulher\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/riscos-digitais-vulnerabilidade-mulher\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/riscos-digitais-vulnerabilidade-mulher\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/capa-YouTube-FINAL-2-1.png\",\"datePublished\":\"2025-04-08T12:48:40+00:00\",\"dateModified\":\"2026-02-20T18:11:27+00:00\",\"description\":\"Podcast discute vulnerabilidade cibern\u00e9tica da mulher e caminhos jur\u00eddicos para prote\u00e7\u00e3o digital e responsabiliza\u00e7\u00e3o.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/riscos-digitais-vulnerabilidade-mulher\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lemosadv.com.br\\\/riscos-digitais-vulnerabilidade-mulher\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/riscos-digitais-vulnerabilidade-mulher\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/capa-YouTube-FINAL-2-1.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/capa-YouTube-FINAL-2-1.png\",\"width\":1920,\"height\":1080,\"caption\":\"vulnerabilidade cibern\u00e9tica mulher\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/riscos-digitais-vulnerabilidade-mulher\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Podcast: Riscos Digitais e a Vulnerabilidade Cibern\u00e9tica da Mulher\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"name\":\"Lemos \u2013 Advocacia para Neg\u00f3cios\",\"description\":\"Escrit\u00f3rio de Advocacia\",\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"alternateName\":\"Lemos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\",\"name\":\"Lemos - Advocacia para neg\u00f3cios\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Lemos - Advocacia para neg\u00f3cios\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/lemosadvocaciaparanegocios\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lemosadv_\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lemosadvocacia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/9d4d106f4f03dbaa7164e5abe5b03894\",\"name\":\"Ana Paula Perez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g\",\"caption\":\"Ana Paula Perez\"},\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/en\\\/author\\\/lemos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"vulnerabilidade cibern\u00e9tica mulher","description":"Podcast discute vulnerabilidade cibern\u00e9tica da mulher e caminhos jur\u00eddicos para prote\u00e7\u00e3o digital e responsabiliza\u00e7\u00e3o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lemosadv.com.br\/riscos-digitais-vulnerabilidade-mulher\/","og_locale":"en_US","og_type":"article","og_title":"vulnerabilidade cibern\u00e9tica mulher","og_description":"Podcast discute vulnerabilidade cibern\u00e9tica da mulher e caminhos jur\u00eddicos para prote\u00e7\u00e3o digital e responsabiliza\u00e7\u00e3o.","og_url":"https:\/\/lemosadv.com.br\/riscos-digitais-vulnerabilidade-mulher\/","og_site_name":"Lemos","article_publisher":"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","article_published_time":"2025-04-08T12:48:40+00:00","article_modified_time":"2026-02-20T18:11:27+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2025\/04\/capa-YouTube-FINAL-2-1.png","type":"image\/png"}],"author":"Ana Paula Perez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ana Paula Perez","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lemosadv.com.br\/riscos-digitais-vulnerabilidade-mulher\/#article","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/riscos-digitais-vulnerabilidade-mulher\/"},"author":{"name":"Ana Paula Perez","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/9d4d106f4f03dbaa7164e5abe5b03894"},"headline":"(pt) Podcast: Riscos Digitais e a Vulnerabilidade Cibern\u00e9tica da Mulher","datePublished":"2025-04-08T12:48:40+00:00","dateModified":"2026-02-20T18:11:27+00:00","mainEntityOfPage":{"@id":"https:\/\/lemosadv.com.br\/riscos-digitais-vulnerabilidade-mulher\/"},"wordCount":38,"publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"image":{"@id":"https:\/\/lemosadv.com.br\/riscos-digitais-vulnerabilidade-mulher\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2025\/04\/capa-YouTube-FINAL-2-1.png","articleSection":["Podcasts"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/lemosadv.com.br\/riscos-digitais-vulnerabilidade-mulher\/","url":"https:\/\/lemosadv.com.br\/riscos-digitais-vulnerabilidade-mulher\/","name":"vulnerabilidade cibern\u00e9tica mulher","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/pb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lemosadv.com.br\/riscos-digitais-vulnerabilidade-mulher\/#primaryimage"},"image":{"@id":"https:\/\/lemosadv.com.br\/riscos-digitais-vulnerabilidade-mulher\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2025\/04\/capa-YouTube-FINAL-2-1.png","datePublished":"2025-04-08T12:48:40+00:00","dateModified":"2026-02-20T18:11:27+00:00","description":"Podcast discute vulnerabilidade cibern\u00e9tica da mulher e caminhos jur\u00eddicos para prote\u00e7\u00e3o digital e responsabiliza\u00e7\u00e3o.","breadcrumb":{"@id":"https:\/\/lemosadv.com.br\/riscos-digitais-vulnerabilidade-mulher\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lemosadv.com.br\/riscos-digitais-vulnerabilidade-mulher\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lemosadv.com.br\/riscos-digitais-vulnerabilidade-mulher\/#primaryimage","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2025\/04\/capa-YouTube-FINAL-2-1.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2025\/04\/capa-YouTube-FINAL-2-1.png","width":1920,"height":1080,"caption":"vulnerabilidade cibern\u00e9tica mulher"},{"@type":"BreadcrumbList","@id":"https:\/\/lemosadv.com.br\/riscos-digitais-vulnerabilidade-mulher\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lemosadv.com.br\/pb\/"},{"@type":"ListItem","position":2,"name":"Podcast: Riscos Digitais e a Vulnerabilidade Cibern\u00e9tica da Mulher"}]},{"@type":"WebSite","@id":"https:\/\/lemosadv.com.br\/pb\/#website","url":"https:\/\/lemosadv.com.br\/pb\/","name":"Lemos \u2013 Advocacia para Neg\u00f3cios","description":"Escrit\u00f3rio de Advocacia","publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"alternateName":"Lemos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lemosadv.com.br\/pb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lemosadv.com.br\/pb\/#organization","name":"Lemos - Advocacia para neg\u00f3cios","url":"https:\/\/lemosadv.com.br\/pb\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","width":512,"height":512,"caption":"Lemos - Advocacia para neg\u00f3cios"},"image":{"@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","https:\/\/www.instagram.com\/lemosadv_\/","https:\/\/www.linkedin.com\/company\/lemosadvocacia"]},{"@type":"Person","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/9d4d106f4f03dbaa7164e5abe5b03894","name":"Ana Paula Perez","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g","caption":"Ana Paula Perez"},"url":"https:\/\/lemosadv.com.br\/en\/author\/lemos\/"}]}},"_links":{"self":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/posts\/752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/comments?post=752"}],"version-history":[{"count":0,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/posts\/752\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/media\/756"}],"wp:attachment":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/media?parent=752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/categories?post=752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/tags?post=752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}