{"id":306,"date":"2024-07-17T11:30:40","date_gmt":"2024-07-17T14:30:40","guid":{"rendered":"https:\/\/lemos.letsite.com.br\/?post_type=profissional&#038;p=306"},"modified":"2026-03-23T11:25:31","modified_gmt":"2026-03-23T14:25:31","slug":"adriana-senna-pessoto-garibe","status":"publish","type":"profissional","link":"https:\/\/lemosadv.com.br\/en\/profissional\/adriana-senna-pessoto-garibe\/","title":{"rendered":"Adriana Senna Pessoto Garibe"},"content":{"rendered":"<p>Law Graduate from Pontif\u00edcia Universidade Cat\u00f3lica de Campinas (Catholic University of Campinas)<\/p>\n<p>Languages: English<\/p>","protected":false},"featured_media":2134,"template":"","tags":[35],"tipo":[5],"alfabeto":[7],"class_list":["post-306","profissional","type-profissional","status-publish","has-post-thumbnail","hentry","tag-direito-digital","tipo-socios-responsaveis","alfabeto-a"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Adriana Senna Pessoto Garibe &#8211; Lemos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lemosadv.com.br\/profissional\/adriana-senna-pessoto-garibe\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adriana Senna Pessoto Garibe &#8211; Lemos\" \/>\n<meta property=\"og:description\" content=\"Law Graduate from Pontif\u00edcia Universidade Cat\u00f3lica de Campinas (Catholic University of Campinas) Languages: English\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lemosadv.com.br\/profissional\/adriana-senna-pessoto-garibe\/\" \/>\n<meta property=\"og:site_name\" content=\"Lemos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T14:25:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/10-1024x754.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"754\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/profissional\\\/adriana-senna-pessoto-garibe\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/profissional\\\/adriana-senna-pessoto-garibe\\\/\",\"name\":\"Adriana Senna Pessoto Garibe &#8211; Lemos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/profissional\\\/adriana-senna-pessoto-garibe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/profissional\\\/adriana-senna-pessoto-garibe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/10.png\",\"datePublished\":\"2024-07-17T14:30:40+00:00\",\"dateModified\":\"2026-03-23T14:25:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/profissional\\\/adriana-senna-pessoto-garibe\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lemosadv.com.br\\\/profissional\\\/adriana-senna-pessoto-garibe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/profissional\\\/adriana-senna-pessoto-garibe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/10.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/10.png\",\"width\":2362,\"height\":1739},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/profissional\\\/adriana-senna-pessoto-garibe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adriana Senna Pessoto Garibe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"name\":\"Lemos \u2013 Advocacia para Neg\u00f3cios\",\"description\":\"Escrit\u00f3rio de Advocacia\",\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"alternateName\":\"Lemos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\",\"name\":\"Lemos - Advocacia para neg\u00f3cios\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Lemos - Advocacia para neg\u00f3cios\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/lemosadvocaciaparanegocios\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lemosadv_\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lemosadvocacia\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adriana Senna Pessoto Garibe &#8211; Lemos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lemosadv.com.br\/profissional\/adriana-senna-pessoto-garibe\/","og_locale":"en_US","og_type":"article","og_title":"Adriana Senna Pessoto Garibe &#8211; Lemos","og_description":"Law Graduate from Pontif\u00edcia Universidade Cat\u00f3lica de Campinas (Catholic University of Campinas) Languages: English","og_url":"https:\/\/lemosadv.com.br\/profissional\/adriana-senna-pessoto-garibe\/","og_site_name":"Lemos","article_publisher":"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","article_modified_time":"2026-03-23T14:25:31+00:00","og_image":[{"width":1024,"height":754,"url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/10-1024x754.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lemosadv.com.br\/profissional\/adriana-senna-pessoto-garibe\/","url":"https:\/\/lemosadv.com.br\/profissional\/adriana-senna-pessoto-garibe\/","name":"Adriana Senna Pessoto Garibe &#8211; Lemos","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/pb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lemosadv.com.br\/profissional\/adriana-senna-pessoto-garibe\/#primaryimage"},"image":{"@id":"https:\/\/lemosadv.com.br\/profissional\/adriana-senna-pessoto-garibe\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/10.png","datePublished":"2024-07-17T14:30:40+00:00","dateModified":"2026-03-23T14:25:31+00:00","breadcrumb":{"@id":"https:\/\/lemosadv.com.br\/profissional\/adriana-senna-pessoto-garibe\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lemosadv.com.br\/profissional\/adriana-senna-pessoto-garibe\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lemosadv.com.br\/profissional\/adriana-senna-pessoto-garibe\/#primaryimage","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/10.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/10.png","width":2362,"height":1739},{"@type":"BreadcrumbList","@id":"https:\/\/lemosadv.com.br\/profissional\/adriana-senna-pessoto-garibe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lemosadv.com.br\/pb\/"},{"@type":"ListItem","position":2,"name":"Adriana Senna Pessoto Garibe"}]},{"@type":"WebSite","@id":"https:\/\/lemosadv.com.br\/pb\/#website","url":"https:\/\/lemosadv.com.br\/pb\/","name":"Lemos \u2013 Advocacia para Neg\u00f3cios","description":"Escrit\u00f3rio de Advocacia","publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"alternateName":"Lemos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lemosadv.com.br\/pb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lemosadv.com.br\/pb\/#organization","name":"Lemos - Advocacia para neg\u00f3cios","url":"https:\/\/lemosadv.com.br\/pb\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","width":512,"height":512,"caption":"Lemos - Advocacia para neg\u00f3cios"},"image":{"@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","https:\/\/www.instagram.com\/lemosadv_\/","https:\/\/www.linkedin.com\/company\/lemosadvocacia"]}]}},"_links":{"self":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/profissional\/306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/profissional"}],"about":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/types\/profissional"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/media\/2134"}],"wp:attachment":[{"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/media?parent=306"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/tags?post=306"},{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/tipo?post=306"},{"taxonomy":"alfabeto","embeddable":true,"href":"https:\/\/lemosadv.com.br\/en\/wp-json\/wp\/v2\/alfabeto?post=306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}