{"id":1244,"date":"2025-07-10T11:11:04","date_gmt":"2025-07-10T14:11:04","guid":{"rendered":"https:\/\/lemosadv.com.br\/?p=1244"},"modified":"2026-02-20T14:42:00","modified_gmt":"2026-02-20T17:42:00","slug":"stf-responsabilidade-plataformas-digitais-2025","status":"publish","type":"post","link":"https:\/\/lemosadv.com.br\/pb\/stf-responsabilidade-plataformas-digitais-2025\/","title":{"rendered":"STF redefine regime de responsabilidade das plataformas digitais e amplia prote\u00e7\u00e3o a direitos fundamentais no ambiente virtual"},"content":{"rendered":"<p><\/p>\n<p class=\"elementToProof\">Em julgamento realizado em 26 de junho de 2025, o Supremo Tribunal Federal reconheceu parcialmente a inconstitucionalidade do artigo 19 do Marco Civil da Internet, ampliando o dever de cuidado das big techs para garantir maior prote\u00e7\u00e3o aos direitos fundamentais dos usu\u00e1rios. Antes da decis\u00e3o, a responsabilidade civil das aplica\u00e7\u00f5es somente ocorria no caso de descumprimento de ordem judicial, com exce\u00e7\u00e3o \u00e0 hip\u00f3tese prevista no artigo 21, referente ao n\u00e3o atendimento de notifica\u00e7\u00e3o extrajudicial.<\/p>\n<p class=\"elementToProof\">Com a nova interpreta\u00e7\u00e3o, os provedores de aplica\u00e7\u00f5es poder\u00e3o ser responsabilizados mesmo sem decis\u00e3o judicial em situa\u00e7\u00f5es espec\u00edficas, como a divulga\u00e7\u00e3o de conte\u00fados pagos ou impulsionados, inclusive por meio de rob\u00f4s ou redes artificiais de distribui\u00e7\u00e3o, salvo se comprovarem que atuaram de forma diligente e em tempo razo\u00e1vel para tornar o conte\u00fado indispon\u00edvel. Tamb\u00e9m poder\u00e3o ser responsabilizados quando deixarem de promover a indisponibiliza\u00e7\u00e3o imediata de conte\u00fados que configurem pr\u00e1ticas de crimes graves, como atos antidemocr\u00e1ticos, terrorismo ou seus preparat\u00f3rios, indu\u00e7\u00e3o ao suic\u00eddio ou \u00e0 automutila\u00e7\u00e3o, discurso de \u00f3dio com base em ra\u00e7a, cor, etnia, religi\u00e3o, proced\u00eancia nacional, sexualidade ou identidade de g\u00eanero, viol\u00eancia contra a mulher, crimes sexuais contra pessoas vulner\u00e1veis, pornografia infantil, crimes graves contra crian\u00e7as e adolescentes e tr\u00e1fico de pessoas. Ressalte-se que a mera exist\u00eancia de conte\u00fado il\u00edcito, de forma isolada, n\u00e3o \u00e9 suficiente, por si s\u00f3, para ensejar a responsabiliza\u00e7\u00e3o civil nessas hip\u00f3teses.<\/p>\n<p class=\"elementToProof\">Al\u00e9m disso, sucessivas replica\u00e7\u00f5es de conte\u00fado ofensivo j\u00e1 reconhecido como il\u00edcito por decis\u00e3o judicial, desde que com conte\u00fado id\u00eantico, dever\u00e3o ser removidas independentemente de nova decis\u00e3o judicial, bastando para isso uma notifica\u00e7\u00e3o judicial ou extrajudicial. O artigo 19 do Marco Civil da Internet permanece aplic\u00e1vel aos provedores de servi\u00e7os de e-mail, \u00e0s plataformas voltadas \u00e0 realiza\u00e7\u00e3o de reuni\u00f5es fechadas por v\u00eddeo ou voz e aos servi\u00e7os de mensageria instant\u00e2nea ou privada. Nos casos de crimes, atos il\u00edcitos ou contas denunciadas como inaut\u00eanticas, aplica-se a regra do artigo 21, sem preju\u00edzo do dever de remo\u00e7\u00e3o do conte\u00fado.<\/p>\n<p class=\"elementToProof\">Os marketplaces passam a responder civilmente com base nas regras do C\u00f3digo de Defesa do Consumidor. Al\u00e9m disso, os provedores dever\u00e3o editar normas internas de autorregula\u00e7\u00e3o que incluam sistema de notifica\u00e7\u00f5es, respeito ao devido processo e elabora\u00e7\u00e3o de relat\u00f3rios anuais de transpar\u00eancia. Tamb\u00e9m dever\u00e3o disponibilizar canais permanentes e acess\u00edveis de atendimento a usu\u00e1rios e n\u00e3o usu\u00e1rios, preferencialmente eletr\u00f4nicos, amplamente divulgados em suas plataformas. \u00c9 exigido que os provedores com atua\u00e7\u00e3o no Brasil mantenham sede e representante no pa\u00eds, com plenos poderes para atua\u00e7\u00e3o.<\/p>\n<p class=\"elementToProof\">Importante destacar que n\u00e3o se aplica responsabilidade objetiva na interpreta\u00e7\u00e3o firmada pelo Supremo Tribunal Federal e que, visando \u00e0 preserva\u00e7\u00e3o da seguran\u00e7a jur\u00eddica, os efeitos da decis\u00e3o valem apenas para o futuro. O STF ainda fez um apelo ao\u00a0 Congresso Nacional\u00a0 para que cumpra seu papel, elaborando\u00a0 uma legisla\u00e7\u00e3o apta a suprir as defici\u00eancias do atual regime jur\u00eddico quanto \u00e0 prote\u00e7\u00e3o de direitos fundamentais no ambiente digital.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Em julgamento realizado em 26 de junho de 2025, o Supremo Tribunal Federal reconheceu parcialmente a inconstitucionalidade do artigo 19 do Marco Civil da Internet, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1245,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[35],"class_list":["post-1244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-direito-digital"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>STF responsabilidade plataformas digitais<\/title>\n<meta name=\"description\" content=\"STF responsabilidade plataformas digitais: decis\u00e3o amplia dever de cuidado das big techs e refor\u00e7a prote\u00e7\u00e3o de direitos fundamentais online.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lemosadv.com.br\/stf-responsabilidade-plataformas-digitais-2025\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"STF responsabilidade plataformas digitais\" \/>\n<meta property=\"og:description\" content=\"STF responsabilidade plataformas digitais: decis\u00e3o amplia dever de cuidado das big techs e refor\u00e7a prote\u00e7\u00e3o de direitos fundamentais online.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lemosadv.com.br\/stf-responsabilidade-plataformas-digitais-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Lemos - Advocacia para neg\u00f3cios\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-10T14:11:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-20T17:42:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2025\/07\/Captura-de-Tela-2025-07-10-as-11.10.27.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1164\" \/>\n\t<meta property=\"og:image:height\" content=\"782\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ana Paula Perez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Paula Perez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/stf-responsabilidade-plataformas-digitais-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/stf-responsabilidade-plataformas-digitais-2025\\\/\"},\"author\":{\"name\":\"Ana Paula Perez\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/9d4d106f4f03dbaa7164e5abe5b03894\"},\"headline\":\"STF redefine regime de responsabilidade das plataformas digitais e amplia prote\u00e7\u00e3o a direitos fundamentais no ambiente virtual\",\"datePublished\":\"2025-07-10T14:11:04+00:00\",\"dateModified\":\"2026-02-20T17:42:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/stf-responsabilidade-plataformas-digitais-2025\\\/\"},\"wordCount\":569,\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/stf-responsabilidade-plataformas-digitais-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Captura-de-Tela-2025-07-10-as-11.10.27.png\",\"keywords\":[\"Direito Digital\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/stf-responsabilidade-plataformas-digitais-2025\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/stf-responsabilidade-plataformas-digitais-2025\\\/\",\"name\":\"STF responsabilidade plataformas digitais\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/stf-responsabilidade-plataformas-digitais-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/stf-responsabilidade-plataformas-digitais-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Captura-de-Tela-2025-07-10-as-11.10.27.png\",\"datePublished\":\"2025-07-10T14:11:04+00:00\",\"dateModified\":\"2026-02-20T17:42:00+00:00\",\"description\":\"STF responsabilidade plataformas digitais: decis\u00e3o amplia dever de cuidado das big techs e refor\u00e7a prote\u00e7\u00e3o de direitos fundamentais online.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/stf-responsabilidade-plataformas-digitais-2025\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lemosadv.com.br\\\/stf-responsabilidade-plataformas-digitais-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/stf-responsabilidade-plataformas-digitais-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Captura-de-Tela-2025-07-10-as-11.10.27.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Captura-de-Tela-2025-07-10-as-11.10.27.png\",\"width\":1164,\"height\":782},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/stf-responsabilidade-plataformas-digitais-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"STF redefine regime de responsabilidade das plataformas digitais e amplia prote\u00e7\u00e3o a direitos fundamentais no ambiente virtual\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"name\":\"Lemos \u2013 Advocacia para Neg\u00f3cios\",\"description\":\"Escrit\u00f3rio de Advocacia\",\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"alternateName\":\"Lemos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\",\"name\":\"Lemos - Advocacia para neg\u00f3cios\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Lemos - Advocacia para neg\u00f3cios\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/lemosadvocaciaparanegocios\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lemosadv_\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lemosadvocacia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/9d4d106f4f03dbaa7164e5abe5b03894\",\"name\":\"Ana Paula Perez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g\",\"caption\":\"Ana Paula Perez\"},\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/author\\\/lemos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"STF responsabilidade plataformas digitais","description":"STF responsabilidade plataformas digitais: decis\u00e3o amplia dever de cuidado das big techs e refor\u00e7a prote\u00e7\u00e3o de direitos fundamentais online.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lemosadv.com.br\/stf-responsabilidade-plataformas-digitais-2025\/","og_locale":"pt_BR","og_type":"article","og_title":"STF responsabilidade plataformas digitais","og_description":"STF responsabilidade plataformas digitais: decis\u00e3o amplia dever de cuidado das big techs e refor\u00e7a prote\u00e7\u00e3o de direitos fundamentais online.","og_url":"https:\/\/lemosadv.com.br\/stf-responsabilidade-plataformas-digitais-2025\/","og_site_name":"Lemos - Advocacia para neg\u00f3cios","article_publisher":"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","article_published_time":"2025-07-10T14:11:04+00:00","article_modified_time":"2026-02-20T17:42:00+00:00","og_image":[{"width":1164,"height":782,"url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2025\/07\/Captura-de-Tela-2025-07-10-as-11.10.27.png","type":"image\/png"}],"author":"Ana Paula Perez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ana Paula Perez","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lemosadv.com.br\/stf-responsabilidade-plataformas-digitais-2025\/#article","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/stf-responsabilidade-plataformas-digitais-2025\/"},"author":{"name":"Ana Paula Perez","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/9d4d106f4f03dbaa7164e5abe5b03894"},"headline":"STF redefine regime de responsabilidade das plataformas digitais e amplia prote\u00e7\u00e3o a direitos fundamentais no ambiente virtual","datePublished":"2025-07-10T14:11:04+00:00","dateModified":"2026-02-20T17:42:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lemosadv.com.br\/stf-responsabilidade-plataformas-digitais-2025\/"},"wordCount":569,"publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"image":{"@id":"https:\/\/lemosadv.com.br\/stf-responsabilidade-plataformas-digitais-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2025\/07\/Captura-de-Tela-2025-07-10-as-11.10.27.png","keywords":["Direito Digital"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/lemosadv.com.br\/stf-responsabilidade-plataformas-digitais-2025\/","url":"https:\/\/lemosadv.com.br\/stf-responsabilidade-plataformas-digitais-2025\/","name":"STF responsabilidade plataformas digitais","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/pb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lemosadv.com.br\/stf-responsabilidade-plataformas-digitais-2025\/#primaryimage"},"image":{"@id":"https:\/\/lemosadv.com.br\/stf-responsabilidade-plataformas-digitais-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2025\/07\/Captura-de-Tela-2025-07-10-as-11.10.27.png","datePublished":"2025-07-10T14:11:04+00:00","dateModified":"2026-02-20T17:42:00+00:00","description":"STF responsabilidade plataformas digitais: decis\u00e3o amplia dever de cuidado das big techs e refor\u00e7a prote\u00e7\u00e3o de direitos fundamentais online.","breadcrumb":{"@id":"https:\/\/lemosadv.com.br\/stf-responsabilidade-plataformas-digitais-2025\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lemosadv.com.br\/stf-responsabilidade-plataformas-digitais-2025\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lemosadv.com.br\/stf-responsabilidade-plataformas-digitais-2025\/#primaryimage","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2025\/07\/Captura-de-Tela-2025-07-10-as-11.10.27.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2025\/07\/Captura-de-Tela-2025-07-10-as-11.10.27.png","width":1164,"height":782},{"@type":"BreadcrumbList","@id":"https:\/\/lemosadv.com.br\/stf-responsabilidade-plataformas-digitais-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lemosadv.com.br\/pb\/"},{"@type":"ListItem","position":2,"name":"STF redefine regime de responsabilidade das plataformas digitais e amplia prote\u00e7\u00e3o a direitos fundamentais no ambiente virtual"}]},{"@type":"WebSite","@id":"https:\/\/lemosadv.com.br\/pb\/#website","url":"https:\/\/lemosadv.com.br\/pb\/","name":"Lemos \u2013 Advocacia para Neg\u00f3cios","description":"Escrit\u00f3rio de Advocacia","publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"alternateName":"Lemos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lemosadv.com.br\/pb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/lemosadv.com.br\/pb\/#organization","name":"Lemos - Advocacia para neg\u00f3cios","url":"https:\/\/lemosadv.com.br\/pb\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","width":512,"height":512,"caption":"Lemos - Advocacia para neg\u00f3cios"},"image":{"@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","https:\/\/www.instagram.com\/lemosadv_\/","https:\/\/www.linkedin.com\/company\/lemosadvocacia"]},{"@type":"Person","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/9d4d106f4f03dbaa7164e5abe5b03894","name":"Ana Paula Perez","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g","caption":"Ana Paula Perez"},"url":"https:\/\/lemosadv.com.br\/pb\/author\/lemos\/"}]}},"_links":{"self":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/1244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/comments?post=1244"}],"version-history":[{"count":1,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/1244\/revisions"}],"predecessor-version":[{"id":1246,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/1244\/revisions\/1246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/media\/1245"}],"wp:attachment":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/media?parent=1244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/categories?post=1244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/tags?post=1244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}