{"id":2043,"date":"2026-03-02T16:51:15","date_gmt":"2026-03-02T19:51:15","guid":{"rendered":"https:\/\/lemosadv.com.br\/?p=2043"},"modified":"2026-03-02T16:52:31","modified_gmt":"2026-03-02T19:52:31","slug":"novas-regras-para-identificacao-de-beneficiario-final","status":"publish","type":"post","link":"https:\/\/lemosadv.com.br\/pb\/novas-regras-para-identificacao-de-beneficiario-final\/","title":{"rendered":"Novas Regras para Identifica\u00e7\u00e3o de Benefici\u00e1rio Final"},"content":{"rendered":"<p>A Receita Federal do Brasil publicou a Instru\u00e7\u00e3o Normativa n\u00ba 2.290, de 30 de outubro de 2025, que alterou a IN RFB n\u00ba 2.119\/2022, \u00a0e trouxe mudan\u00e7as relevantes nas regras de identifica\u00e7\u00e3o e reporte do Benefici\u00e1rio Final.<\/p>\n<p>A nova norma refor\u00e7a as exig\u00eancias de transpar\u00eancia societ\u00e1ria e est\u00e1 alinhada \u00e0s recomenda\u00e7\u00f5es internacionais de preven\u00e7\u00e3o \u00e0 lavagem de dinheiro, ao financiamento do terrorismo, \u00e0 oculta\u00e7\u00e3o patrimonial e \u00e0 evas\u00e3o fiscal.<\/p>\n<p>Com a nova regulamenta\u00e7\u00e3o, as entidades obrigadas passam a prestar informa\u00e7\u00f5es exclusivamente por meio do <strong>Formul\u00e1rio Digital de Benefici\u00e1rios Finais (e-BEF)<\/strong>, ferramenta eletr\u00f4nica oficial da Receita Federal, que dever\u00e1 ser preenchida, mantida atualizada e monitorada de forma cont\u00ednua.<\/p>\n<ul>\n<li>As informa\u00e7\u00f5es sobre o benefici\u00e1rio final devem ser prestadas:<\/li>\n<li>em at\u00e9 30 dias contados da inscri\u00e7\u00e3o no CNPJ; ou<\/li>\n<li>de qualquer altera\u00e7\u00e3o na condi\u00e7\u00e3o de benefici\u00e1rio final;<\/li>\n<li>anualmente, at\u00e9 o \u00faltimo dia \u00fatil de cada ano-calend\u00e1rio, mesmo que n\u00e3o haja altera\u00e7\u00f5es em rela\u00e7\u00e3o \u00e0s informa\u00e7\u00f5es anteriormente declaradas.<\/li>\n<\/ul>\n<p>A atualiza\u00e7\u00e3o \u00e9 obrigat\u00f3ria sempre que houver mudan\u00e7a na participa\u00e7\u00e3o societ\u00e1ria, estrutura de controle, ou qualquer outro elemento relevante para a caracteriza\u00e7\u00e3o do benefici\u00e1rio final.<\/p>\n<p>O n\u00e3o cumprimento das obriga\u00e7\u00f5es previstas na IN RFB n\u00ba 2.290\/2025 pode resultar, entre outras medidas, em: suspens\u00e3o da inscri\u00e7\u00e3o no CNPJ, restri\u00e7\u00f5es \u00e0 pr\u00e1tica de atos societ\u00e1rios e registros p\u00fablicos, impedimento para emiss\u00e3o de certid\u00f5es de regularidade e responsabiliza\u00e7\u00e3o administrativa, tribut\u00e1ria e, em casos mais graves, responsabiliza\u00e7\u00e3o penal, especialmente quando houver presta\u00e7\u00e3o de informa\u00e7\u00f5es falsas ou omiss\u00e3o de dados relevantes.<\/p>\n<p>A IN RFB n\u00ba 2.290\/2025 representa um avan\u00e7o significativo no fortalecimento da transpar\u00eancia societ\u00e1ria no Brasil, inaugurando uma nova fase de reporte digital mais rigorosa, peri\u00f3dica e com maior grau de responsabiliza\u00e7\u00e3o.<\/p>\n<p>Diante desse cen\u00e1rio, recomenda-se que as sociedades promovam a adequada organiza\u00e7\u00e3o documental, e adotem monitoramento permanente das informa\u00e7\u00f5es relacionadas ao benefici\u00e1rio final.<\/p>","protected":false},"excerpt":{"rendered":"<p>A Receita Federal do Brasil publicou a Instru\u00e7\u00e3o Normativa n\u00ba 2.290, de 30 de outubro de 2025, que alterou a IN RFB n\u00ba 2.119\/2022, \u00a0e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2045,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[33],"class_list":["post-2043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","tag-direito-societario"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novas Regras para Identifica\u00e7\u00e3o de Benefici\u00e1rio Final &#8211; Lemos - Advocacia para neg\u00f3cios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lemosadv.com.br\/novas-regras-para-identificacao-de-beneficiario-final\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:pb]Novas Regras para Identifica\u00e7\u00e3o de Benefici\u00e1rio Final[:] &#8211; Lemos - Advocacia para neg\u00f3cios\" \/>\n<meta property=\"og:description\" content=\"A Receita Federal do Brasil publicou a Instru\u00e7\u00e3o Normativa n\u00ba 2.290, de 30 de outubro de 2025, que alterou a IN RFB n\u00ba 2.119\/2022, \u00a0e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lemosadv.com.br\/novas-regras-para-identificacao-de-beneficiario-final\/\" \/>\n<meta property=\"og:site_name\" content=\"Lemos - Advocacia para neg\u00f3cios\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-02T19:51:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-02T19:52:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/rfb-1-1024x613-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"613\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ana Paula Perez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Paula Perez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/novas-regras-para-identificacao-de-beneficiario-final\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/novas-regras-para-identificacao-de-beneficiario-final\\\/\"},\"author\":{\"name\":\"Ana Paula Perez\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/9d4d106f4f03dbaa7164e5abe5b03894\"},\"headline\":\"Novas Regras para Identifica\u00e7\u00e3o de Benefici\u00e1rio Final\",\"datePublished\":\"2026-03-02T19:51:15+00:00\",\"dateModified\":\"2026-03-02T19:52:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/novas-regras-para-identificacao-de-beneficiario-final\\\/\"},\"wordCount\":354,\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/novas-regras-para-identificacao-de-beneficiario-final\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/rfb-1-1024x613-1.jpg\",\"keywords\":[\"Direito Societ\u00e1rio\"],\"articleSection\":[\"Artigos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/novas-regras-para-identificacao-de-beneficiario-final\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/novas-regras-para-identificacao-de-beneficiario-final\\\/\",\"name\":\"[:pb]Novas Regras para Identifica\u00e7\u00e3o de Benefici\u00e1rio Final[:] &#8211; Lemos - Advocacia para neg\u00f3cios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/novas-regras-para-identificacao-de-beneficiario-final\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/novas-regras-para-identificacao-de-beneficiario-final\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/rfb-1-1024x613-1.jpg\",\"datePublished\":\"2026-03-02T19:51:15+00:00\",\"dateModified\":\"2026-03-02T19:52:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/novas-regras-para-identificacao-de-beneficiario-final\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lemosadv.com.br\\\/novas-regras-para-identificacao-de-beneficiario-final\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/novas-regras-para-identificacao-de-beneficiario-final\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/rfb-1-1024x613-1.jpg\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/rfb-1-1024x613-1.jpg\",\"width\":1024,\"height\":613,\"caption\":\"Superintend\u00eancia da Receita Federal, em Bras\u00edlia.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/novas-regras-para-identificacao-de-beneficiario-final\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novas Regras para Identifica\u00e7\u00e3o de Benefici\u00e1rio Final\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"name\":\"Lemos \u2013 Advocacia para Neg\u00f3cios\",\"description\":\"Escrit\u00f3rio de Advocacia\",\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"alternateName\":\"Lemos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\",\"name\":\"Lemos - Advocacia para neg\u00f3cios\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Lemos - Advocacia para neg\u00f3cios\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/lemosadvocaciaparanegocios\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lemosadv_\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lemosadvocacia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/9d4d106f4f03dbaa7164e5abe5b03894\",\"name\":\"Ana Paula Perez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g\",\"caption\":\"Ana Paula Perez\"},\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/author\\\/lemos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:pb]Novas Regras para Identifica\u00e7\u00e3o de Benefici\u00e1rio Final[:] &#8211; Lemos - Advocacia para neg\u00f3cios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lemosadv.com.br\/novas-regras-para-identificacao-de-beneficiario-final\/","og_locale":"pt_BR","og_type":"article","og_title":"[:pb]Novas Regras para Identifica\u00e7\u00e3o de Benefici\u00e1rio Final[:] &#8211; Lemos - Advocacia para neg\u00f3cios","og_description":"A Receita Federal do Brasil publicou a Instru\u00e7\u00e3o Normativa n\u00ba 2.290, de 30 de outubro de 2025, que alterou a IN RFB n\u00ba 2.119\/2022, \u00a0e [&hellip;]","og_url":"https:\/\/lemosadv.com.br\/novas-regras-para-identificacao-de-beneficiario-final\/","og_site_name":"Lemos - Advocacia para neg\u00f3cios","article_publisher":"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","article_published_time":"2026-03-02T19:51:15+00:00","article_modified_time":"2026-03-02T19:52:31+00:00","og_image":[{"width":1024,"height":613,"url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/rfb-1-1024x613-1.jpg","type":"image\/jpeg"}],"author":"Ana Paula Perez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ana Paula Perez","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lemosadv.com.br\/novas-regras-para-identificacao-de-beneficiario-final\/#article","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/novas-regras-para-identificacao-de-beneficiario-final\/"},"author":{"name":"Ana Paula Perez","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/9d4d106f4f03dbaa7164e5abe5b03894"},"headline":"Novas Regras para Identifica\u00e7\u00e3o de Benefici\u00e1rio Final","datePublished":"2026-03-02T19:51:15+00:00","dateModified":"2026-03-02T19:52:31+00:00","mainEntityOfPage":{"@id":"https:\/\/lemosadv.com.br\/novas-regras-para-identificacao-de-beneficiario-final\/"},"wordCount":354,"publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"image":{"@id":"https:\/\/lemosadv.com.br\/novas-regras-para-identificacao-de-beneficiario-final\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/rfb-1-1024x613-1.jpg","keywords":["Direito Societ\u00e1rio"],"articleSection":["Artigos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/lemosadv.com.br\/novas-regras-para-identificacao-de-beneficiario-final\/","url":"https:\/\/lemosadv.com.br\/novas-regras-para-identificacao-de-beneficiario-final\/","name":"[:pb]Novas Regras para Identifica\u00e7\u00e3o de Benefici\u00e1rio Final[:] &#8211; Lemos - Advocacia para neg\u00f3cios","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/pb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lemosadv.com.br\/novas-regras-para-identificacao-de-beneficiario-final\/#primaryimage"},"image":{"@id":"https:\/\/lemosadv.com.br\/novas-regras-para-identificacao-de-beneficiario-final\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/rfb-1-1024x613-1.jpg","datePublished":"2026-03-02T19:51:15+00:00","dateModified":"2026-03-02T19:52:31+00:00","breadcrumb":{"@id":"https:\/\/lemosadv.com.br\/novas-regras-para-identificacao-de-beneficiario-final\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lemosadv.com.br\/novas-regras-para-identificacao-de-beneficiario-final\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lemosadv.com.br\/novas-regras-para-identificacao-de-beneficiario-final\/#primaryimage","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/rfb-1-1024x613-1.jpg","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/rfb-1-1024x613-1.jpg","width":1024,"height":613,"caption":"Superintend\u00eancia da Receita Federal, em Bras\u00edlia."},{"@type":"BreadcrumbList","@id":"https:\/\/lemosadv.com.br\/novas-regras-para-identificacao-de-beneficiario-final\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lemosadv.com.br\/pb\/"},{"@type":"ListItem","position":2,"name":"Novas Regras para Identifica\u00e7\u00e3o de Benefici\u00e1rio Final"}]},{"@type":"WebSite","@id":"https:\/\/lemosadv.com.br\/pb\/#website","url":"https:\/\/lemosadv.com.br\/pb\/","name":"Lemos \u2013 Advocacia para Neg\u00f3cios","description":"Escrit\u00f3rio de Advocacia","publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"alternateName":"Lemos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lemosadv.com.br\/pb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/lemosadv.com.br\/pb\/#organization","name":"Lemos - Advocacia para neg\u00f3cios","url":"https:\/\/lemosadv.com.br\/pb\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","width":512,"height":512,"caption":"Lemos - Advocacia para neg\u00f3cios"},"image":{"@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","https:\/\/www.instagram.com\/lemosadv_\/","https:\/\/www.linkedin.com\/company\/lemosadvocacia"]},{"@type":"Person","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/9d4d106f4f03dbaa7164e5abe5b03894","name":"Ana Paula Perez","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g","caption":"Ana Paula Perez"},"url":"https:\/\/lemosadv.com.br\/pb\/author\/lemos\/"}]}},"_links":{"self":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/2043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/comments?post=2043"}],"version-history":[{"count":1,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/2043\/revisions"}],"predecessor-version":[{"id":2044,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/2043\/revisions\/2044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/media\/2045"}],"wp:attachment":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/media?parent=2043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/categories?post=2043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/tags?post=2043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}