{"id":2051,"date":"2026-03-05T17:18:01","date_gmt":"2026-03-05T20:18:01","guid":{"rendered":"https:\/\/lemosadv.com.br\/?p=2051"},"modified":"2026-03-17T16:25:06","modified_gmt":"2026-03-17T19:25:06","slug":"politica-de-inteligencia-artificial-nos-orgaos-publicos","status":"publish","type":"post","link":"https:\/\/lemosadv.com.br\/pb\/politica-de-inteligencia-artificial-nos-orgaos-publicos\/","title":{"rendered":"Pol\u00edtica de Intelig\u00eancia Artificial nos \u00f3rg\u00e3os p\u00fablicos"},"content":{"rendered":"<p>A Receita Federal deu um passo importante em governan\u00e7a de IA: a Portaria RFB n\u00ba 647, publicada em fevereiro, define regras e salvaguardas para o desenvolvimento e uso de solu\u00e7\u00f5es de Intelig\u00eancia Artificial. Na pr\u00e1tica, o texto refor\u00e7a limites, responsabilidades e controles, especialmente para IA generativa.<\/p>\n<p>Dois dispositivos merecem aten\u00e7\u00e3o imediata. O art. 5\u00ba deixa expl\u00edcito que a IA n\u00e3o substitui, n\u00e3o condiciona e nem vincula o exerc\u00edcio das compet\u00eancias legais do agente p\u00fablico e que a decis\u00e3o final e o ato administrativo permanecem sob responsabilidade humana, com ju\u00edzo cr\u00edtico e independente. J\u00e1 o art. 6\u00ba veda sistemas de IA incompat\u00edveis com direitos fundamentais, valores democr\u00e1ticos e garantias constitucionais, citando exemplos como manipula\u00e7\u00e3o subliminar, pontua\u00e7\u00e3o social e vigil\u00e2ncia massiva e indiscriminada.<\/p>\n<p>Al\u00e9m disso, o artigo 11 assegura que as solu\u00e7\u00f5es de IA generativa no \u00e2mbito da Secretaria Especial da Receita Federal do Brasil dever\u00e3o possuir controles adicionais proporcionais ao risco, de responsabilidade da \u00e1rea de neg\u00f3cio, incluindo a designa\u00e7\u00e3o de curador, a defini\u00e7\u00e3o do n\u00edvel de acur\u00e1cia aceit\u00e1vel e o monitoramento cont\u00ednuo dos resultados produzidos.<\/p>\n<p>Outrossim, o cap\u00edtulo IV, que trata do desenvolvimento e tratamento de modelos de IA, indica alguns importantes princ\u00edpios para o desenvolvimento, como a utiliza\u00e7\u00e3o de amostras de dados e prioriza\u00e7\u00e3o de modelos de IA que viabilizem explicabilidade e auditabilidade. Os cap\u00edtulos seguintes tratam do uso de solu\u00e7\u00f5es de IA, a auditoria, e o treinamento, bem como o uso com princ\u00edpios \u00e9ticos. A aplica\u00e7\u00e3o desta portaria na contrata\u00e7\u00e3o de modelos de IA se tornou necess\u00e1ria e, caso haja descumprimento desta e das demais normas, ficar\u00e1 caracterizada a infra\u00e7\u00e3o funcional, a ser apurada em processo administrativo disciplinar, sem preju\u00edzo da aplica\u00e7\u00e3o das responsabilidades penal e civil.<\/p>\n<p class=\"elementToProof\">Em resumo, a Portaria RFB n\u00ba 647 sinaliza uma diretriz clara: IA s\u00f3 \u00e9 admiss\u00edvel com governan\u00e7a, controles e responsabiliza\u00e7\u00e3o. Para organiza\u00e7\u00f5es que desenvolvem, contratam ou operam solu\u00e7\u00f5es de IA, especialmente generativa, o recado \u00e9 direto: <b>adequa\u00e7\u00e3o jur\u00eddica e compliance s\u00e3o indispens\u00e1veis.\u00a0<\/b><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>A Receita Federal deu um passo importante em governan\u00e7a de IA: a Portaria RFB n\u00ba 647, publicada em fevereiro, define regras e salvaguardas para o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[35],"class_list":["post-2051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","tag-direito-digital"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de Intelig\u00eancia Artificial nos \u00f3rg\u00e3os p\u00fablicos &#8211; Lemos - Advocacia para neg\u00f3cios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lemosadv.com.br\/politica-de-inteligencia-artificial-nos-orgaos-publicos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:pb]Pol\u00edtica de Intelig\u00eancia Artificial nos \u00f3rg\u00e3os p\u00fablicos[:] &#8211; Lemos - Advocacia para neg\u00f3cios\" \/>\n<meta property=\"og:description\" content=\"A Receita Federal deu um passo importante em governan\u00e7a de IA: a Portaria RFB n\u00ba 647, publicada em fevereiro, define regras e salvaguardas para o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lemosadv.com.br\/politica-de-inteligencia-artificial-nos-orgaos-publicos\/\" \/>\n<meta property=\"og:site_name\" content=\"Lemos - Advocacia para neg\u00f3cios\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-05T20:18:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-17T19:25:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/Captura-de-Tela-2026-03-17-as-16.23.32-1024x565.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"565\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ana Paula Perez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Paula Perez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/politica-de-inteligencia-artificial-nos-orgaos-publicos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/politica-de-inteligencia-artificial-nos-orgaos-publicos\\\/\"},\"author\":{\"name\":\"Ana Paula Perez\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/9d4d106f4f03dbaa7164e5abe5b03894\"},\"headline\":\"Pol\u00edtica de Intelig\u00eancia Artificial nos \u00f3rg\u00e3os p\u00fablicos\",\"datePublished\":\"2026-03-05T20:18:01+00:00\",\"dateModified\":\"2026-03-17T19:25:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/politica-de-inteligencia-artificial-nos-orgaos-publicos\\\/\"},\"wordCount\":379,\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/politica-de-inteligencia-artificial-nos-orgaos-publicos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Captura-de-Tela-2026-03-17-as-16.23.32.png\",\"keywords\":[\"Direito Digital\"],\"articleSection\":[\"Artigos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/politica-de-inteligencia-artificial-nos-orgaos-publicos\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/politica-de-inteligencia-artificial-nos-orgaos-publicos\\\/\",\"name\":\"[:pb]Pol\u00edtica de Intelig\u00eancia Artificial nos \u00f3rg\u00e3os p\u00fablicos[:] &#8211; Lemos - Advocacia para neg\u00f3cios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/politica-de-inteligencia-artificial-nos-orgaos-publicos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/politica-de-inteligencia-artificial-nos-orgaos-publicos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Captura-de-Tela-2026-03-17-as-16.23.32.png\",\"datePublished\":\"2026-03-05T20:18:01+00:00\",\"dateModified\":\"2026-03-17T19:25:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/politica-de-inteligencia-artificial-nos-orgaos-publicos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lemosadv.com.br\\\/politica-de-inteligencia-artificial-nos-orgaos-publicos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/politica-de-inteligencia-artificial-nos-orgaos-publicos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Captura-de-Tela-2026-03-17-as-16.23.32.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Captura-de-Tela-2026-03-17-as-16.23.32.png\",\"width\":2394,\"height\":1320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/politica-de-inteligencia-artificial-nos-orgaos-publicos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de Intelig\u00eancia Artificial nos \u00f3rg\u00e3os p\u00fablicos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"name\":\"Lemos \u2013 Advocacia para Neg\u00f3cios\",\"description\":\"Escrit\u00f3rio de Advocacia\",\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"alternateName\":\"Lemos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\",\"name\":\"Lemos - Advocacia para neg\u00f3cios\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Lemos - Advocacia para neg\u00f3cios\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/lemosadvocaciaparanegocios\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lemosadv_\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lemosadvocacia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/9d4d106f4f03dbaa7164e5abe5b03894\",\"name\":\"Ana Paula Perez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g\",\"caption\":\"Ana Paula Perez\"},\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/author\\\/lemos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:pb]Pol\u00edtica de Intelig\u00eancia Artificial nos \u00f3rg\u00e3os p\u00fablicos[:] &#8211; Lemos - Advocacia para neg\u00f3cios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lemosadv.com.br\/politica-de-inteligencia-artificial-nos-orgaos-publicos\/","og_locale":"pt_BR","og_type":"article","og_title":"[:pb]Pol\u00edtica de Intelig\u00eancia Artificial nos \u00f3rg\u00e3os p\u00fablicos[:] &#8211; Lemos - Advocacia para neg\u00f3cios","og_description":"A Receita Federal deu um passo importante em governan\u00e7a de IA: a Portaria RFB n\u00ba 647, publicada em fevereiro, define regras e salvaguardas para o [&hellip;]","og_url":"https:\/\/lemosadv.com.br\/politica-de-inteligencia-artificial-nos-orgaos-publicos\/","og_site_name":"Lemos - Advocacia para neg\u00f3cios","article_publisher":"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","article_published_time":"2026-03-05T20:18:01+00:00","article_modified_time":"2026-03-17T19:25:06+00:00","og_image":[{"width":1024,"height":565,"url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/Captura-de-Tela-2026-03-17-as-16.23.32-1024x565.png","type":"image\/png"}],"author":"Ana Paula Perez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ana Paula Perez","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lemosadv.com.br\/politica-de-inteligencia-artificial-nos-orgaos-publicos\/#article","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/politica-de-inteligencia-artificial-nos-orgaos-publicos\/"},"author":{"name":"Ana Paula Perez","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/9d4d106f4f03dbaa7164e5abe5b03894"},"headline":"Pol\u00edtica de Intelig\u00eancia Artificial nos \u00f3rg\u00e3os p\u00fablicos","datePublished":"2026-03-05T20:18:01+00:00","dateModified":"2026-03-17T19:25:06+00:00","mainEntityOfPage":{"@id":"https:\/\/lemosadv.com.br\/politica-de-inteligencia-artificial-nos-orgaos-publicos\/"},"wordCount":379,"publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"image":{"@id":"https:\/\/lemosadv.com.br\/politica-de-inteligencia-artificial-nos-orgaos-publicos\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/Captura-de-Tela-2026-03-17-as-16.23.32.png","keywords":["Direito Digital"],"articleSection":["Artigos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/lemosadv.com.br\/politica-de-inteligencia-artificial-nos-orgaos-publicos\/","url":"https:\/\/lemosadv.com.br\/politica-de-inteligencia-artificial-nos-orgaos-publicos\/","name":"[:pb]Pol\u00edtica de Intelig\u00eancia Artificial nos \u00f3rg\u00e3os p\u00fablicos[:] &#8211; Lemos - Advocacia para neg\u00f3cios","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/pb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lemosadv.com.br\/politica-de-inteligencia-artificial-nos-orgaos-publicos\/#primaryimage"},"image":{"@id":"https:\/\/lemosadv.com.br\/politica-de-inteligencia-artificial-nos-orgaos-publicos\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/Captura-de-Tela-2026-03-17-as-16.23.32.png","datePublished":"2026-03-05T20:18:01+00:00","dateModified":"2026-03-17T19:25:06+00:00","breadcrumb":{"@id":"https:\/\/lemosadv.com.br\/politica-de-inteligencia-artificial-nos-orgaos-publicos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lemosadv.com.br\/politica-de-inteligencia-artificial-nos-orgaos-publicos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lemosadv.com.br\/politica-de-inteligencia-artificial-nos-orgaos-publicos\/#primaryimage","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/Captura-de-Tela-2026-03-17-as-16.23.32.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/Captura-de-Tela-2026-03-17-as-16.23.32.png","width":2394,"height":1320},{"@type":"BreadcrumbList","@id":"https:\/\/lemosadv.com.br\/politica-de-inteligencia-artificial-nos-orgaos-publicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lemosadv.com.br\/pb\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de Intelig\u00eancia Artificial nos \u00f3rg\u00e3os p\u00fablicos"}]},{"@type":"WebSite","@id":"https:\/\/lemosadv.com.br\/pb\/#website","url":"https:\/\/lemosadv.com.br\/pb\/","name":"Lemos \u2013 Advocacia para Neg\u00f3cios","description":"Escrit\u00f3rio de Advocacia","publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"alternateName":"Lemos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lemosadv.com.br\/pb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/lemosadv.com.br\/pb\/#organization","name":"Lemos - Advocacia para neg\u00f3cios","url":"https:\/\/lemosadv.com.br\/pb\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","width":512,"height":512,"caption":"Lemos - Advocacia para neg\u00f3cios"},"image":{"@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","https:\/\/www.instagram.com\/lemosadv_\/","https:\/\/www.linkedin.com\/company\/lemosadvocacia"]},{"@type":"Person","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/9d4d106f4f03dbaa7164e5abe5b03894","name":"Ana Paula Perez","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g","caption":"Ana Paula Perez"},"url":"https:\/\/lemosadv.com.br\/pb\/author\/lemos\/"}]}},"_links":{"self":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/2051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/comments?post=2051"}],"version-history":[{"count":1,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/2051\/revisions"}],"predecessor-version":[{"id":2052,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/2051\/revisions\/2052"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/media\/2089"}],"wp:attachment":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/media?parent=2051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/categories?post=2051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/tags?post=2051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}