{"id":2152,"date":"2026-03-23T13:57:56","date_gmt":"2026-03-23T16:57:56","guid":{"rendered":"https:\/\/lemosadv.com.br\/?p=2152"},"modified":"2026-03-23T14:11:40","modified_gmt":"2026-03-23T17:11:40","slug":"podcast-a-reforma-tributaria-e-o-planejamento-sucessorio","status":"publish","type":"post","link":"https:\/\/lemosadv.com.br\/pb\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\/","title":{"rendered":"Podcast: A Reforma Tribut\u00e1ria e o Planejamento sucess\u00f3rio"},"content":{"rendered":"<p>A advogada Ana L\u00facia Juliani, da \u00e1rea societ\u00e1ria doLemos Advocacia para Neg\u00f3cios, recebe Abelardo Lemos, s\u00f3cio da \u00e1rea de Direito Tribut\u00e1rio, para uma conversa sobre a Reforma Tribut\u00e1ria e seus impactos no planejamentosucess\u00f3rio.<br \/>\nO epis\u00f3dio aborda como as mudan\u00e7as em discuss\u00e3o afetam holdings familiares, doa\u00e7\u00f5es, tributa\u00e7\u00e3o de lucros e dividendos, ITCMD e estrat\u00e9gias de sucess\u00e3o patrimonial, destacando o que permanece v\u00e1lido, o que exige revis\u00e3o e a import\u00e2ncia de decis\u00f5es alinhadas \u00e0 seguran\u00e7a jur\u00eddica diante de um cen\u00e1rio ainda em regulamenta\u00e7\u00e3o.<\/p>","protected":false},"excerpt":{"rendered":"<p>A advogada Ana L\u00facia Juliani, da \u00e1rea societ\u00e1ria doLemos Advocacia para Neg\u00f3cios, recebe Abelardo Lemos, s\u00f3cio da \u00e1rea de Direito Tribut\u00e1rio, para uma conversa sobre [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2159,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[43],"tags":[],"class_list":["post-2152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcasts"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Podcast: A Reforma Tribut\u00e1ria e o Planejamento sucess\u00f3rio &#8211; Lemos - Advocacia para neg\u00f3cios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lemosadv.com.br\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:pb]Podcast: A Reforma Tribut\u00e1ria e o Planejamento sucess\u00f3rio[:] &#8211; Lemos - Advocacia para neg\u00f3cios\" \/>\n<meta property=\"og:description\" content=\"A advogada Ana L\u00facia Juliani, da \u00e1rea societ\u00e1ria doLemos Advocacia para Neg\u00f3cios, recebe Abelardo Lemos, s\u00f3cio da \u00e1rea de Direito Tribut\u00e1rio, para uma conversa sobre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lemosadv.com.br\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\/\" \/>\n<meta property=\"og:site_name\" content=\"Lemos - Advocacia para neg\u00f3cios\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-23T16:57:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T17:11:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/Captura-de-Tela-2026-03-23-as-14.10.36.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1458\" \/>\n\t<meta property=\"og:image:height\" content=\"814\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Iago Davanzo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Iago Davanzo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\\\/\"},\"author\":{\"name\":\"Iago Davanzo\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/61b670e4e09ada92988ec2c705314e06\"},\"headline\":\"Podcast: A Reforma Tribut\u00e1ria e o Planejamento sucess\u00f3rio\",\"datePublished\":\"2026-03-23T16:57:56+00:00\",\"dateModified\":\"2026-03-23T17:11:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\\\/\"},\"wordCount\":114,\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Captura-de-Tela-2026-03-23-as-14.10.36.png\",\"articleSection\":[\"Podcasts\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\\\/\",\"name\":\"[:pb]Podcast: A Reforma Tribut\u00e1ria e o Planejamento sucess\u00f3rio[:] &#8211; Lemos - Advocacia para neg\u00f3cios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Captura-de-Tela-2026-03-23-as-14.10.36.png\",\"datePublished\":\"2026-03-23T16:57:56+00:00\",\"dateModified\":\"2026-03-23T17:11:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lemosadv.com.br\\\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Captura-de-Tela-2026-03-23-as-14.10.36.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Captura-de-Tela-2026-03-23-as-14.10.36.png\",\"width\":1458,\"height\":814},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Podcast: A Reforma Tribut\u00e1ria e o Planejamento sucess\u00f3rio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"name\":\"Lemos \u2013 Advocacia para Neg\u00f3cios\",\"description\":\"Escrit\u00f3rio de Advocacia\",\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"alternateName\":\"Lemos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\",\"name\":\"Lemos - Advocacia para neg\u00f3cios\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Lemos - Advocacia para neg\u00f3cios\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/lemosadvocaciaparanegocios\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lemosadv_\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lemosadvocacia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/61b670e4e09ada92988ec2c705314e06\",\"name\":\"Iago Davanzo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d86440cfa722a901b66428cdf7cfee4dd0a6b4ca2643b56d59b0267d9c8fca9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d86440cfa722a901b66428cdf7cfee4dd0a6b4ca2643b56d59b0267d9c8fca9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d86440cfa722a901b66428cdf7cfee4dd0a6b4ca2643b56d59b0267d9c8fca9?s=96&d=mm&r=g\",\"caption\":\"Iago Davanzo\"},\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/author\\\/canal\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:pb]Podcast: A Reforma Tribut\u00e1ria e o Planejamento sucess\u00f3rio[:] &#8211; Lemos - Advocacia para neg\u00f3cios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lemosadv.com.br\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\/","og_locale":"pt_BR","og_type":"article","og_title":"[:pb]Podcast: A Reforma Tribut\u00e1ria e o Planejamento sucess\u00f3rio[:] &#8211; Lemos - Advocacia para neg\u00f3cios","og_description":"A advogada Ana L\u00facia Juliani, da \u00e1rea societ\u00e1ria doLemos Advocacia para Neg\u00f3cios, recebe Abelardo Lemos, s\u00f3cio da \u00e1rea de Direito Tribut\u00e1rio, para uma conversa sobre [&hellip;]","og_url":"https:\/\/lemosadv.com.br\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\/","og_site_name":"Lemos - Advocacia para neg\u00f3cios","article_publisher":"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","article_published_time":"2026-03-23T16:57:56+00:00","article_modified_time":"2026-03-23T17:11:40+00:00","og_image":[{"width":1458,"height":814,"url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/Captura-de-Tela-2026-03-23-as-14.10.36.png","type":"image\/png"}],"author":"Iago Davanzo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Iago Davanzo","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lemosadv.com.br\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\/#article","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\/"},"author":{"name":"Iago Davanzo","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/61b670e4e09ada92988ec2c705314e06"},"headline":"Podcast: A Reforma Tribut\u00e1ria e o Planejamento sucess\u00f3rio","datePublished":"2026-03-23T16:57:56+00:00","dateModified":"2026-03-23T17:11:40+00:00","mainEntityOfPage":{"@id":"https:\/\/lemosadv.com.br\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\/"},"wordCount":114,"publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"image":{"@id":"https:\/\/lemosadv.com.br\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/Captura-de-Tela-2026-03-23-as-14.10.36.png","articleSection":["Podcasts"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/lemosadv.com.br\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\/","url":"https:\/\/lemosadv.com.br\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\/","name":"[:pb]Podcast: A Reforma Tribut\u00e1ria e o Planejamento sucess\u00f3rio[:] &#8211; Lemos - Advocacia para neg\u00f3cios","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/pb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lemosadv.com.br\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\/#primaryimage"},"image":{"@id":"https:\/\/lemosadv.com.br\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/Captura-de-Tela-2026-03-23-as-14.10.36.png","datePublished":"2026-03-23T16:57:56+00:00","dateModified":"2026-03-23T17:11:40+00:00","breadcrumb":{"@id":"https:\/\/lemosadv.com.br\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lemosadv.com.br\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lemosadv.com.br\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\/#primaryimage","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/Captura-de-Tela-2026-03-23-as-14.10.36.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2026\/03\/Captura-de-Tela-2026-03-23-as-14.10.36.png","width":1458,"height":814},{"@type":"BreadcrumbList","@id":"https:\/\/lemosadv.com.br\/podcast-a-reforma-tributaria-e-o-planejamento-sucessorio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lemosadv.com.br\/pb\/"},{"@type":"ListItem","position":2,"name":"Podcast: A Reforma Tribut\u00e1ria e o Planejamento sucess\u00f3rio"}]},{"@type":"WebSite","@id":"https:\/\/lemosadv.com.br\/pb\/#website","url":"https:\/\/lemosadv.com.br\/pb\/","name":"Lemos \u2013 Advocacia para Neg\u00f3cios","description":"Escrit\u00f3rio de Advocacia","publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"alternateName":"Lemos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lemosadv.com.br\/pb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/lemosadv.com.br\/pb\/#organization","name":"Lemos - Advocacia para neg\u00f3cios","url":"https:\/\/lemosadv.com.br\/pb\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","width":512,"height":512,"caption":"Lemos - Advocacia para neg\u00f3cios"},"image":{"@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","https:\/\/www.instagram.com\/lemosadv_\/","https:\/\/www.linkedin.com\/company\/lemosadvocacia"]},{"@type":"Person","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/61b670e4e09ada92988ec2c705314e06","name":"Iago Davanzo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3d86440cfa722a901b66428cdf7cfee4dd0a6b4ca2643b56d59b0267d9c8fca9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3d86440cfa722a901b66428cdf7cfee4dd0a6b4ca2643b56d59b0267d9c8fca9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3d86440cfa722a901b66428cdf7cfee4dd0a6b4ca2643b56d59b0267d9c8fca9?s=96&d=mm&r=g","caption":"Iago Davanzo"},"url":"https:\/\/lemosadv.com.br\/pb\/author\/canal\/"}]}},"_links":{"self":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/2152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/comments?post=2152"}],"version-history":[{"count":1,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/2152\/revisions"}],"predecessor-version":[{"id":2153,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/2152\/revisions\/2153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/media\/2159"}],"wp:attachment":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/media?parent=2152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/categories?post=2152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/tags?post=2152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}