{"id":265,"date":"2024-06-19T19:52:47","date_gmt":"2024-06-19T22:52:47","guid":{"rendered":"https:\/\/lemos.letsite.com.br\/?p=265"},"modified":"2024-07-04T19:53:53","modified_gmt":"2024-07-04T22:53:53","slug":"aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4","status":"publish","type":"post","link":"https:\/\/lemosadv.com.br\/pb\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\/","title":{"rendered":"Aplica\u00e7\u00e3o do c\u00f3digo de defesa do consumidor no e-commerce #3TEMP #EP4"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":300,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[43],"tags":[],"class_list":["post-265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcasts"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aplica\u00e7\u00e3o do c\u00f3digo de defesa do consumidor no e-commerce #3TEMP #EP4 &#8211; Lemos - Advocacia para neg\u00f3cios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lemosadv.com.br\/en\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:pb]Aplica\u00e7\u00e3o do c\u00f3digo de defesa do consumidor no e-commerce #3TEMP #EP4[:] &#8211; Lemos - Advocacia para neg\u00f3cios\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lemosadv.com.br\/en\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\/\" \/>\n<meta property=\"og:site_name\" content=\"Lemos - Advocacia para neg\u00f3cios\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-19T22:52:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-04T22:53:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/podcasts.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"807\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/en\\\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/en\\\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/d596db55770da72ca6d193b9667d8b51\"},\"headline\":\"Aplica\u00e7\u00e3o do c\u00f3digo de defesa do consumidor no e-commerce #3TEMP #EP4\",\"datePublished\":\"2024-06-19T22:52:47+00:00\",\"dateModified\":\"2024-07-04T22:53:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/en\\\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\\\/\"},\"wordCount\":14,\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/en\\\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/podcasts.jpg\",\"articleSection\":[\"Podcasts\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/en\\\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/en\\\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\\\/\",\"name\":\"[:pb]Aplica\u00e7\u00e3o do c\u00f3digo de defesa do consumidor no e-commerce #3TEMP #EP4[:] &#8211; Lemos - Advocacia para neg\u00f3cios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/en\\\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/en\\\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/podcasts.jpg\",\"datePublished\":\"2024-06-19T22:52:47+00:00\",\"dateModified\":\"2024-07-04T22:53:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/en\\\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lemosadv.com.br\\\/en\\\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/en\\\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/podcasts.jpg\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/podcasts.jpg\",\"width\":807,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/en\\\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"(pt) Aplica\u00e7\u00e3o do c\u00f3digo de defesa do consumidor no e-commerce #3TEMP #EP4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"name\":\"Lemos \u2013 Advocacia para Neg\u00f3cios\",\"description\":\"Escrit\u00f3rio de Advocacia\",\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"alternateName\":\"Lemos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\",\"name\":\"Lemos - Advocacia para neg\u00f3cios\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Lemos - Advocacia para neg\u00f3cios\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/lemosadvocaciaparanegocios\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lemosadv_\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lemosadvocacia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/d596db55770da72ca6d193b9667d8b51\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/lemos.letsite.com.br\"],\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:pb]Aplica\u00e7\u00e3o do c\u00f3digo de defesa do consumidor no e-commerce #3TEMP #EP4[:] &#8211; Lemos - Advocacia para neg\u00f3cios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lemosadv.com.br\/en\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\/","og_locale":"pt_BR","og_type":"article","og_title":"[:pb]Aplica\u00e7\u00e3o do c\u00f3digo de defesa do consumidor no e-commerce #3TEMP #EP4[:] &#8211; Lemos - Advocacia para neg\u00f3cios","og_url":"https:\/\/lemosadv.com.br\/en\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\/","og_site_name":"Lemos - Advocacia para neg\u00f3cios","article_publisher":"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","article_published_time":"2024-06-19T22:52:47+00:00","article_modified_time":"2024-07-04T22:53:53+00:00","og_image":[{"width":807,"height":480,"url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/podcasts.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lemosadv.com.br\/en\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\/#article","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/en\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\/"},"author":{"name":"admin","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/d596db55770da72ca6d193b9667d8b51"},"headline":"Aplica\u00e7\u00e3o do c\u00f3digo de defesa do consumidor no e-commerce #3TEMP #EP4","datePublished":"2024-06-19T22:52:47+00:00","dateModified":"2024-07-04T22:53:53+00:00","mainEntityOfPage":{"@id":"https:\/\/lemosadv.com.br\/en\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\/"},"wordCount":14,"publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"image":{"@id":"https:\/\/lemosadv.com.br\/en\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/podcasts.jpg","articleSection":["Podcasts"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/lemosadv.com.br\/en\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\/","url":"https:\/\/lemosadv.com.br\/en\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\/","name":"[:pb]Aplica\u00e7\u00e3o do c\u00f3digo de defesa do consumidor no e-commerce #3TEMP #EP4[:] &#8211; Lemos - Advocacia para neg\u00f3cios","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/pb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lemosadv.com.br\/en\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\/#primaryimage"},"image":{"@id":"https:\/\/lemosadv.com.br\/en\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/podcasts.jpg","datePublished":"2024-06-19T22:52:47+00:00","dateModified":"2024-07-04T22:53:53+00:00","breadcrumb":{"@id":"https:\/\/lemosadv.com.br\/en\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lemosadv.com.br\/en\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lemosadv.com.br\/en\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\/#primaryimage","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/podcasts.jpg","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/podcasts.jpg","width":807,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/lemosadv.com.br\/en\/aplicacao-do-codigo-de-defesa-do-consumidor-no-e-commerce-3temp-ep4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lemosadv.com.br\/pb\/"},{"@type":"ListItem","position":2,"name":"(pt) Aplica\u00e7\u00e3o do c\u00f3digo de defesa do consumidor no e-commerce #3TEMP #EP4"}]},{"@type":"WebSite","@id":"https:\/\/lemosadv.com.br\/pb\/#website","url":"https:\/\/lemosadv.com.br\/pb\/","name":"Lemos \u2013 Advocacia para Neg\u00f3cios","description":"Escrit\u00f3rio de Advocacia","publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"alternateName":"Lemos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lemosadv.com.br\/pb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/lemosadv.com.br\/pb\/#organization","name":"Lemos - Advocacia para neg\u00f3cios","url":"https:\/\/lemosadv.com.br\/pb\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","width":512,"height":512,"caption":"Lemos - Advocacia para neg\u00f3cios"},"image":{"@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","https:\/\/www.instagram.com\/lemosadv_\/","https:\/\/www.linkedin.com\/company\/lemosadvocacia"]},{"@type":"Person","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/d596db55770da72ca6d193b9667d8b51","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/lemos.letsite.com.br"],"url":"https:\/\/lemosadv.com.br\/pb\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/comments?post=265"}],"version-history":[{"count":1,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/265\/revisions"}],"predecessor-version":[{"id":266,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/265\/revisions\/266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/media\/300"}],"wp:attachment":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/media?parent=265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/categories?post=265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/tags?post=265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}