{"id":330,"date":"2024-07-15T13:56:50","date_gmt":"2024-07-15T16:56:50","guid":{"rendered":"https:\/\/lemos.letsite.com.br\/?p=330"},"modified":"2024-07-17T13:58:06","modified_gmt":"2024-07-17T16:58:06","slug":"evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima","status":"publish","type":"post","link":"https:\/\/lemosadv.com.br\/pb\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\/","title":{"rendered":"Evento Clim\u00e1tico no Rio Grande do Sul Acelera o Debate e \u00c9 Publicada a Lei N\u00ba 14.904\/24 que Trata da Adapta\u00e7\u00e3o \u00e0s Mudan\u00e7as do Clima"},"content":{"rendered":"<p>Foi publicada no dia 28\/06\/24, a Lei n\u00ba 14.904\/24 que estabelece diretrizes para a elabora\u00e7\u00e3o de planos de adapta\u00e7\u00e3o \u00e0s mudan\u00e7as do clima.<\/p>\n<p>Tal norma decorre do recente evento clim\u00e1tico agudo ocorrido no Estado do Rio Grande do Sul e que, recentemente, completou 02 (dois) meses. Em raz\u00e3o disso, a lei em quest\u00e3o teve a sua tramita\u00e7\u00e3o legislativa acelerada, dado o elevado risco de novas ocorr\u00eancias clim\u00e1ticas no territ\u00f3rio nacional.<\/p>\n<p>Diante disso, \u00e9 necess\u00e1rio planejar as pol\u00edticas p\u00fablicas de adapta\u00e7\u00e3o ao \u00e1rduo desafio das altera\u00e7\u00f5es de temperatura e clima que estamos vivendo.<\/p>\n<p>O objetivo central da norma \u00e9 implementar medidas para reduzir a vulnerabilidade e a exposi\u00e7\u00e3o a riscos dos sistemas ambiental, social, econ\u00f4mico e de infraestrutura diante dos efeitos adversos atuais e esperados da mudan\u00e7a do clima, com fundamento na Lei n\u00ba 12.187\/2009 que institui a Pol\u00edtica Nacional sobre Mudan\u00e7a do Clima (PNMC).<\/p>\n<p>Os planos e as pol\u00edticas p\u00fablicas setoriais e tem\u00e1ticas existentes e as estrat\u00e9gias de desenvolvimento local, municipal, estadual, regional e nacional incluir\u00e3o a gest\u00e3o do risco da mudan\u00e7a do clima em seus escopos.<\/p>\n<p>Visando uma integra\u00e7\u00e3o da estrat\u00e9gia, os planos de adapta\u00e7\u00e3o dever\u00e3o integrar-se aos planos sobre mudan\u00e7a do clima que contemplem medidas de mitiga\u00e7\u00e3o de emiss\u00f5es de gases de efeito estufa.<\/p>\n<p>As principais diretrizes dos planos de adapta\u00e7\u00e3o s\u00e3o: (i) preventivo e corretivo de enfrentamento aos desastres naturais e diminui\u00e7\u00e3o da vulnerabilidade e da exposi\u00e7\u00e3o dos sistemas ambiental, social, econ\u00f4mico e de infraestrutura, em \u00e1reas rurais e urbanas; (ii) priorizar a gest\u00e3o coordenada de investimentos, com base no grau de vulnerabilidade, de modo a estimar, minimizar ou evitar perdas; (iii) estabelecer instrumentos de enfrentamento, visando a efic\u00e1cia dos referidos sistemas; (iv) integrar estrat\u00e9gias de mitiga\u00e7\u00e3o e adapta\u00e7\u00e3o em todos os n\u00edveis, em alinhamento com os compromissos assumidos no Acordo de Paris; (v) fomento \u00e0 an\u00e1lises de risco de vulnerabilidades clim\u00e1ticas; (vi) sinergia entre as Defesas Civis; (vii) estimular a adapta\u00e7\u00e3o do setor agropecu\u00e1rio \u00e0 economia de baixo carbono; (viii) buscar solu\u00e7\u00f5es de adapta\u00e7\u00e3o na natureza; (ix) monitoramento e avalia\u00e7\u00e3o; (x) a\u00e7\u00f5es de P&amp;D \u2013 Pesquisa e Desenvolvimento.<\/p>\n<p>O foco \u00e9 implementar as estrat\u00e9gias lan\u00e7adas na infraestrutura urbana (saneamento, habita\u00e7\u00e3o e outros), na infraestrutura nacional (energia, transporte e outros) e na infraestrutura baseada na pr\u00f3pria natureza, por meio do uso dos elementos que a pr\u00f3pria natureza fornece.<\/p>\n<p>A proposta \u00e9 que tenhamos um grande plano nacional de adapta\u00e7\u00e3o \u00e0 mudan\u00e7a do clima, a ser elaborado pelo governo federal em articula\u00e7\u00e3o com demais entes e setores econ\u00f4micos e sociais, priorizando munic\u00edpios mais vulner\u00e1veis e expostos \u00e0s amea\u00e7as clim\u00e1ticas, fomentando cons\u00f3rcios intermunicipais e arranjos regionais para a consecu\u00e7\u00e3o das medidas por ele previstas, assim como planos estaduais, distrital e municipais.<\/p>\n<p>O art. 7\u00ba da lei disp\u00f5e que, independentemente, dos planos de adapta\u00e7\u00e3o previstos na norma, a identifica\u00e7\u00e3o de vulnerabilidades e a gest\u00e3o do risco clim\u00e1tico dever\u00e3o ser levadas em considera\u00e7\u00e3o nas pol\u00edticas setoriais e nas pol\u00edticas de desenvolvimento e de ordenamento territorial.<\/p>\n<p>Neste ponto, o maior risco \u00e9 o de altera\u00e7\u00e3o na sistem\u00e1tica e regramento dos licenciamentos ambientais, uma vez que h\u00e1 quem defenda que os licenciamentos ambientais tenham um cap\u00edtulo ou momento processual que verse sobre mudan\u00e7as clim\u00e1ticas.<\/p>","protected":false},"excerpt":{"rendered":"<p>Foi publicada no dia 28\/06\/24, a Lei n\u00ba 14.904\/24 que estabelece diretrizes para a elabora\u00e7\u00e3o de planos de adapta\u00e7\u00e3o \u00e0s mudan\u00e7as do clima. Tal norma [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":332,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[36],"class_list":["post-330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","tag-direito-ambiental-e-sustentabilidade"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evento Clim\u00e1tico no Rio Grande do Sul Acelera o Debate e \u00c9 Publicada a Lei N\u00ba 14.904\/24 que Trata da Adapta\u00e7\u00e3o \u00e0s Mudan\u00e7as do Clima &#8211; Lemos - Advocacia para neg\u00f3cios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lemosadv.com.br\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:pb]Evento Clim\u00e1tico no Rio Grande do Sul Acelera o Debate e \u00c9 Publicada a Lei N\u00ba 14.904\/24 que Trata da Adapta\u00e7\u00e3o \u00e0s Mudan\u00e7as do Clima[:] &#8211; Lemos - Advocacia para neg\u00f3cios\" \/>\n<meta property=\"og:description\" content=\"Foi publicada no dia 28\/06\/24, a Lei n\u00ba 14.904\/24 que estabelece diretrizes para a elabora\u00e7\u00e3o de planos de adapta\u00e7\u00e3o \u00e0s mudan\u00e7as do clima. Tal norma [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lemosadv.com.br\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\/\" \/>\n<meta property=\"og:site_name\" content=\"Lemos - Advocacia para neg\u00f3cios\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-15T16:56:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-17T16:58:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/rs.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"807\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/d596db55770da72ca6d193b9667d8b51\"},\"headline\":\"Evento Clim\u00e1tico no Rio Grande do Sul Acelera o Debate e \u00c9 Publicada a Lei N\u00ba 14.904\\\/24 que Trata da Adapta\u00e7\u00e3o \u00e0s Mudan\u00e7as do Clima\",\"datePublished\":\"2024-07-15T16:56:50+00:00\",\"dateModified\":\"2024-07-17T16:58:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\\\/\"},\"wordCount\":619,\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/rs.jpg\",\"keywords\":[\"Direito Ambiental e Sustentabilidade\"],\"articleSection\":[\"Artigos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\\\/\",\"name\":\"[:pb]Evento Clim\u00e1tico no Rio Grande do Sul Acelera o Debate e \u00c9 Publicada a Lei N\u00ba 14.904\\\/24 que Trata da Adapta\u00e7\u00e3o \u00e0s Mudan\u00e7as do Clima[:] &#8211; Lemos - Advocacia para neg\u00f3cios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/rs.jpg\",\"datePublished\":\"2024-07-15T16:56:50+00:00\",\"dateModified\":\"2024-07-17T16:58:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lemosadv.com.br\\\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/rs.jpg\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/rs.jpg\",\"width\":807,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evento Clim\u00e1tico no Rio Grande do Sul Acelera o Debate e \u00c9 Publicada a Lei N\u00ba 14.904\\\/24 que Trata da Adapta\u00e7\u00e3o \u00e0s Mudan\u00e7as do Clima\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"name\":\"Lemos \u2013 Advocacia para Neg\u00f3cios\",\"description\":\"Escrit\u00f3rio de Advocacia\",\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"alternateName\":\"Lemos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\",\"name\":\"Lemos - Advocacia para neg\u00f3cios\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Lemos - Advocacia para neg\u00f3cios\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/lemosadvocaciaparanegocios\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lemosadv_\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lemosadvocacia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/d596db55770da72ca6d193b9667d8b51\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/lemos.letsite.com.br\"],\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:pb]Evento Clim\u00e1tico no Rio Grande do Sul Acelera o Debate e \u00c9 Publicada a Lei N\u00ba 14.904\/24 que Trata da Adapta\u00e7\u00e3o \u00e0s Mudan\u00e7as do Clima[:] &#8211; Lemos - Advocacia para neg\u00f3cios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lemosadv.com.br\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\/","og_locale":"pt_BR","og_type":"article","og_title":"[:pb]Evento Clim\u00e1tico no Rio Grande do Sul Acelera o Debate e \u00c9 Publicada a Lei N\u00ba 14.904\/24 que Trata da Adapta\u00e7\u00e3o \u00e0s Mudan\u00e7as do Clima[:] &#8211; Lemos - Advocacia para neg\u00f3cios","og_description":"Foi publicada no dia 28\/06\/24, a Lei n\u00ba 14.904\/24 que estabelece diretrizes para a elabora\u00e7\u00e3o de planos de adapta\u00e7\u00e3o \u00e0s mudan\u00e7as do clima. Tal norma [&hellip;]","og_url":"https:\/\/lemosadv.com.br\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\/","og_site_name":"Lemos - Advocacia para neg\u00f3cios","article_publisher":"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","article_published_time":"2024-07-15T16:56:50+00:00","article_modified_time":"2024-07-17T16:58:06+00:00","og_image":[{"width":807,"height":480,"url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/rs.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lemosadv.com.br\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\/#article","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\/"},"author":{"name":"admin","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/d596db55770da72ca6d193b9667d8b51"},"headline":"Evento Clim\u00e1tico no Rio Grande do Sul Acelera o Debate e \u00c9 Publicada a Lei N\u00ba 14.904\/24 que Trata da Adapta\u00e7\u00e3o \u00e0s Mudan\u00e7as do Clima","datePublished":"2024-07-15T16:56:50+00:00","dateModified":"2024-07-17T16:58:06+00:00","mainEntityOfPage":{"@id":"https:\/\/lemosadv.com.br\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\/"},"wordCount":619,"publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"image":{"@id":"https:\/\/lemosadv.com.br\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/rs.jpg","keywords":["Direito Ambiental e Sustentabilidade"],"articleSection":["Artigos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/lemosadv.com.br\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\/","url":"https:\/\/lemosadv.com.br\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\/","name":"[:pb]Evento Clim\u00e1tico no Rio Grande do Sul Acelera o Debate e \u00c9 Publicada a Lei N\u00ba 14.904\/24 que Trata da Adapta\u00e7\u00e3o \u00e0s Mudan\u00e7as do Clima[:] &#8211; Lemos - Advocacia para neg\u00f3cios","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/pb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lemosadv.com.br\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\/#primaryimage"},"image":{"@id":"https:\/\/lemosadv.com.br\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/rs.jpg","datePublished":"2024-07-15T16:56:50+00:00","dateModified":"2024-07-17T16:58:06+00:00","breadcrumb":{"@id":"https:\/\/lemosadv.com.br\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lemosadv.com.br\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lemosadv.com.br\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\/#primaryimage","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/rs.jpg","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/rs.jpg","width":807,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/lemosadv.com.br\/evento-climatico-no-rio-grande-do-sul-acelera-o-debate-e-e-publicada-a-lei-no-14-904-24-que-trata-da-adaptacao-as-mudancas-do-clima\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lemosadv.com.br\/pb\/"},{"@type":"ListItem","position":2,"name":"Evento Clim\u00e1tico no Rio Grande do Sul Acelera o Debate e \u00c9 Publicada a Lei N\u00ba 14.904\/24 que Trata da Adapta\u00e7\u00e3o \u00e0s Mudan\u00e7as do Clima"}]},{"@type":"WebSite","@id":"https:\/\/lemosadv.com.br\/pb\/#website","url":"https:\/\/lemosadv.com.br\/pb\/","name":"Lemos \u2013 Advocacia para Neg\u00f3cios","description":"Escrit\u00f3rio de Advocacia","publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"alternateName":"Lemos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lemosadv.com.br\/pb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/lemosadv.com.br\/pb\/#organization","name":"Lemos - Advocacia para neg\u00f3cios","url":"https:\/\/lemosadv.com.br\/pb\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","width":512,"height":512,"caption":"Lemos - Advocacia para neg\u00f3cios"},"image":{"@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","https:\/\/www.instagram.com\/lemosadv_\/","https:\/\/www.linkedin.com\/company\/lemosadvocacia"]},{"@type":"Person","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/d596db55770da72ca6d193b9667d8b51","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/lemos.letsite.com.br"],"url":"https:\/\/lemosadv.com.br\/pb\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/comments?post=330"}],"version-history":[{"count":1,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/330\/revisions"}],"predecessor-version":[{"id":331,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/330\/revisions\/331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/media\/332"}],"wp:attachment":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/media?parent=330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/categories?post=330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/tags?post=330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}