{"id":525,"date":"2024-10-07T14:31:17","date_gmt":"2024-10-07T17:31:17","guid":{"rendered":"https:\/\/lemosadv.com.br\/?p=525"},"modified":"2024-10-07T14:34:15","modified_gmt":"2024-10-07T17:34:15","slug":"a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes","status":"publish","type":"post","link":"https:\/\/lemosadv.com.br\/pb\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\/","title":{"rendered":"A responsabilidade das empresas, seus s\u00f3cios e administradores no cumprimento das obriga\u00e7\u00f5es atinentes \u00e0 log\u00edstica reversa dos seus produtos e componentes"},"content":{"rendered":"<p><\/p>\n<p style=\"font-weight: 400;\">Dados do SINIR &#8211; Sistema Nacional de Informa\u00e7\u00f5es sobre a Gest\u00e3o dos Res\u00edduos S\u00f3lidos, demonstram o crescimento ano a ano do volume de res\u00edduos s\u00f3lidos reaproveitados, reciclados e adequadamente destinados do ponto de vista ambiental. Al\u00e9m disso, temos visto a crescente ades\u00e3o dos setores econ\u00f4micos aos sistemas de log\u00edstica reversa previstos na Lei n\u00ba 12.305\/2010 (Pol\u00edtica Nacional de Res\u00edduos S\u00f3lidos &#8211; PNRS). Atualmente, est\u00e3o estruturados e implementados em \u00e2mbito nacional os sistemas de log\u00edstica reversa referentes aos res\u00edduos e embalagens dos setores\/produtos como agrot\u00f3xicos, baterias de chumbo \u00e1cido, eletr\u00f4nicos, embalagens de a\u00e7o, \u00f3leo lubrificante usado ou contaminado, embalagens em geral, l\u00e2mpadas, medicamentos, embalagem pl\u00e1stica de \u00f3leo lubrificante, pilhas e baterias, pneus inserv\u00edveis, e latas de alum\u00ednio para bebidas.<\/p>\n<p style=\"font-weight: 400;\">Por\u00e9m, o ponto de aten\u00e7\u00e3o \u00e9 evidenciar \u00e0s empresas, seus acionistas e administradores as responsabilidades de cada um em caso de descumprimento da norma. O art. 51 da Lei n\u00ba 12.305\/2010, estabelece que \u201c<em>sem preju\u00edzo da obriga\u00e7\u00e3o de, independentemente da exist\u00eancia de culpa, reparar os danos causados, a a\u00e7\u00e3o ou omiss\u00e3o das pessoas f\u00edsicas ou jur\u00eddicas, sujeita os infratores \u00e0s san\u00e7\u00f5es penais e administrativas derivadas de condutas e atividades lesivas ao meio ambiente<\/em>\u201d.<\/p>\n<p style=\"font-weight: 400;\">No caso dos res\u00edduos s\u00f3lidos, a Lei n\u00ba 9.605\/1998 considera em seu art. 54, \u00a72\u00ba como crime pun\u00edvel com pena de reclus\u00e3o de um a cinco anos, \u201c<em>causar polui\u00e7\u00e3o de qualquer natureza (\u2026) por lan\u00e7amento de res\u00edduos s\u00f3lidos (\u2026) em desacordo com as exig\u00eancias legais<\/em>\u201d. A pena por crime ambiental pode atingir, al\u00e9m da pessoa jur\u00eddica, o diretor, o administrador, o membro de conselho e de \u00f3rg\u00e3o t\u00e9cnico, o auditor, o gerente, o preposto ou mandat\u00e1rio de pessoa jur\u00eddica, que, sabendo da conduta criminosa de outrem, deixar de impedir a sua pr\u00e1tica, quando podia agir para evit\u00e1-la.<\/p>\n<p style=\"font-weight: 400;\">Outra modalidade de responsabilidade inerente \u00e0 inobserv\u00e2ncia das regras atinentes aos res\u00edduos s\u00f3lidos \u00e9 a administrativa, pun\u00edvel na forma de infra\u00e7\u00f5es cominadas pelo \u00f3rg\u00e3o ambiental, que variam desde \u00e0 advert\u00eancia \u00e0 multa simples ou di\u00e1ria. Por fim, h\u00e1 ainda a previs\u00e3o legal de responsabiliza\u00e7\u00e3o civil da pessoa jur\u00eddica por danos causados ao meio ambiente.<\/p>\n<p style=\"font-weight: 400;\">A responsabilidade das empresas em cumprir com as disposi\u00e7\u00f5es da PNRS, em especial daquelas que possuem sistemas de log\u00edstica reversa implementados, tem reverberado tamb\u00e9m no licenciamento ambiental. Os \u00f3rg\u00e3os ambientais t\u00eam exigido pa\u00eds afora a comprova\u00e7\u00e3o do cumprimento da log\u00edstica reversa em rela\u00e7\u00e3o aos produtos e seus componentes como item obrigat\u00f3rio para obten\u00e7\u00e3o ou renova\u00e7\u00e3o da Licen\u00e7a de Opera\u00e7\u00e3o \u2013 LO do empreendimento.<\/p>\n<p style=\"font-weight: 400;\">No Estado de S\u00e3o Paulo, a recente Decis\u00e3o de Diretoria CETESB n\u00ba 051\/2024\/P, estabelece que a n\u00e3o comprova\u00e7\u00e3o das obriga\u00e7\u00f5es da log\u00edstica reversa ou o n\u00e3o atingimento das metas estabelecidas pelo empreendimento no Plano de Log\u00edstica Reversa, poder\u00e3o impactar o licenciamento ambiental. Ademais, os empreendimentos infratores estar\u00e3o sujeitos a multa administrativa entre R$ 5.000,00 (cinco mil reais) e R$ 50.000.000,00 (cinquenta milh\u00f5es de reais).<\/p>\n<p style=\"font-weight: 400;\">Considerando que a demonstra\u00e7\u00e3o de cumprimento da Log\u00edstica Reversa poder\u00e1 se dar por meio de Declara\u00e7\u00e3o de Detentores da Marca\u00a0 quanto \u00e0 participa\u00e7\u00e3o em sistemas de log\u00edstica reversa ou da Declara\u00e7\u00e3o Anual de Embalagens Colocadas no Mercado, ou ainda por meio ades\u00e3o a Plano de Log\u00edstica Reversa e respectivos Relat\u00f3rios Anuais de Resultados, \u00e9 fundamental que as empresas estejam atentas \u00e0s suas obriga\u00e7\u00f5es de log\u00edstica reversa, revisitem ou elaborem estrat\u00e9gias e Planos de Log\u00edstica Reversa conforme determina a legisla\u00e7\u00e3o vigente e deem evid\u00eancias de cumprimento das regras, sejam elas federais, estaduais ou municipais, a fim de mitigar riscos de responsabiliza\u00e7\u00e3o e de comprometimento do licenciamento ambiental do seu empreendimento.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Dados do SINIR &#8211; Sistema Nacional de Informa\u00e7\u00f5es sobre a Gest\u00e3o dos Res\u00edduos S\u00f3lidos, demonstram o crescimento ano a ano do volume de res\u00edduos s\u00f3lidos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":528,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[36],"class_list":["post-525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","tag-direito-ambiental-e-sustentabilidade"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A responsabilidade das empresas, seus s\u00f3cios e administradores no cumprimento das obriga\u00e7\u00f5es atinentes \u00e0 log\u00edstica reversa dos seus produtos e componentes &#8211; Lemos - Advocacia para neg\u00f3cios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lemosadv.com.br\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:pb]A responsabilidade das empresas, seus s\u00f3cios e administradores no cumprimento das obriga\u00e7\u00f5es atinentes \u00e0 log\u00edstica reversa dos seus produtos e componentes[:] &#8211; Lemos - Advocacia para neg\u00f3cios\" \/>\n<meta property=\"og:description\" content=\"Dados do SINIR &#8211; Sistema Nacional de Informa\u00e7\u00f5es sobre a Gest\u00e3o dos Res\u00edduos S\u00f3lidos, demonstram o crescimento ano a ano do volume de res\u00edduos s\u00f3lidos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lemosadv.com.br\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\/\" \/>\n<meta property=\"og:site_name\" content=\"Lemos - Advocacia para neg\u00f3cios\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-07T17:31:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-07T17:34:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/10\/FOTO_1@4x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"717\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Ana Paula Perez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Paula Perez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\\\/\"},\"author\":{\"name\":\"Ana Paula Perez\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/9d4d106f4f03dbaa7164e5abe5b03894\"},\"headline\":\"A responsabilidade das empresas, seus s\u00f3cios e administradores no cumprimento das obriga\u00e7\u00f5es atinentes \u00e0 log\u00edstica reversa dos seus produtos e componentes\",\"datePublished\":\"2024-10-07T17:31:17+00:00\",\"dateModified\":\"2024-10-07T17:34:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\\\/\"},\"wordCount\":688,\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/FOTO_1@4x.webp\",\"keywords\":[\"Direito Ambiental e Sustentabilidade\"],\"articleSection\":[\"Artigos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\\\/\",\"name\":\"[:pb]A responsabilidade das empresas, seus s\u00f3cios e administradores no cumprimento das obriga\u00e7\u00f5es atinentes \u00e0 log\u00edstica reversa dos seus produtos e componentes[:] &#8211; Lemos - Advocacia para neg\u00f3cios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/FOTO_1@4x.webp\",\"datePublished\":\"2024-10-07T17:31:17+00:00\",\"dateModified\":\"2024-10-07T17:34:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lemosadv.com.br\\\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/FOTO_1@4x.webp\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/FOTO_1@4x.webp\",\"width\":1024,\"height\":717},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A responsabilidade das empresas, seus s\u00f3cios e administradores no cumprimento das obriga\u00e7\u00f5es atinentes \u00e0 log\u00edstica reversa dos seus produtos e componentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"name\":\"Lemos \u2013 Advocacia para Neg\u00f3cios\",\"description\":\"Escrit\u00f3rio de Advocacia\",\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"alternateName\":\"Lemos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\",\"name\":\"Lemos - Advocacia para neg\u00f3cios\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Lemos - Advocacia para neg\u00f3cios\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/lemosadvocaciaparanegocios\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lemosadv_\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lemosadvocacia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/9d4d106f4f03dbaa7164e5abe5b03894\",\"name\":\"Ana Paula Perez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g\",\"caption\":\"Ana Paula Perez\"},\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/author\\\/lemos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:pb]A responsabilidade das empresas, seus s\u00f3cios e administradores no cumprimento das obriga\u00e7\u00f5es atinentes \u00e0 log\u00edstica reversa dos seus produtos e componentes[:] &#8211; Lemos - Advocacia para neg\u00f3cios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lemosadv.com.br\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\/","og_locale":"pt_BR","og_type":"article","og_title":"[:pb]A responsabilidade das empresas, seus s\u00f3cios e administradores no cumprimento das obriga\u00e7\u00f5es atinentes \u00e0 log\u00edstica reversa dos seus produtos e componentes[:] &#8211; Lemos - Advocacia para neg\u00f3cios","og_description":"Dados do SINIR &#8211; Sistema Nacional de Informa\u00e7\u00f5es sobre a Gest\u00e3o dos Res\u00edduos S\u00f3lidos, demonstram o crescimento ano a ano do volume de res\u00edduos s\u00f3lidos [&hellip;]","og_url":"https:\/\/lemosadv.com.br\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\/","og_site_name":"Lemos - Advocacia para neg\u00f3cios","article_publisher":"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","article_published_time":"2024-10-07T17:31:17+00:00","article_modified_time":"2024-10-07T17:34:15+00:00","og_image":[{"width":1024,"height":717,"url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/10\/FOTO_1@4x.webp","type":"image\/webp"}],"author":"Ana Paula Perez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ana Paula Perez","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lemosadv.com.br\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\/#article","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\/"},"author":{"name":"Ana Paula Perez","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/9d4d106f4f03dbaa7164e5abe5b03894"},"headline":"A responsabilidade das empresas, seus s\u00f3cios e administradores no cumprimento das obriga\u00e7\u00f5es atinentes \u00e0 log\u00edstica reversa dos seus produtos e componentes","datePublished":"2024-10-07T17:31:17+00:00","dateModified":"2024-10-07T17:34:15+00:00","mainEntityOfPage":{"@id":"https:\/\/lemosadv.com.br\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\/"},"wordCount":688,"publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"image":{"@id":"https:\/\/lemosadv.com.br\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/10\/FOTO_1@4x.webp","keywords":["Direito Ambiental e Sustentabilidade"],"articleSection":["Artigos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/lemosadv.com.br\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\/","url":"https:\/\/lemosadv.com.br\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\/","name":"[:pb]A responsabilidade das empresas, seus s\u00f3cios e administradores no cumprimento das obriga\u00e7\u00f5es atinentes \u00e0 log\u00edstica reversa dos seus produtos e componentes[:] &#8211; Lemos - Advocacia para neg\u00f3cios","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/pb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lemosadv.com.br\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\/#primaryimage"},"image":{"@id":"https:\/\/lemosadv.com.br\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/10\/FOTO_1@4x.webp","datePublished":"2024-10-07T17:31:17+00:00","dateModified":"2024-10-07T17:34:15+00:00","breadcrumb":{"@id":"https:\/\/lemosadv.com.br\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lemosadv.com.br\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lemosadv.com.br\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\/#primaryimage","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/10\/FOTO_1@4x.webp","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/10\/FOTO_1@4x.webp","width":1024,"height":717},{"@type":"BreadcrumbList","@id":"https:\/\/lemosadv.com.br\/a-responsabilidade-das-empresas-seus-socios-e-administradores-no-cumprimento-das-obrigacoes-atinentes-a-logistica-reversa-dos-seus-produtos-e-componentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lemosadv.com.br\/pb\/"},{"@type":"ListItem","position":2,"name":"A responsabilidade das empresas, seus s\u00f3cios e administradores no cumprimento das obriga\u00e7\u00f5es atinentes \u00e0 log\u00edstica reversa dos seus produtos e componentes"}]},{"@type":"WebSite","@id":"https:\/\/lemosadv.com.br\/pb\/#website","url":"https:\/\/lemosadv.com.br\/pb\/","name":"Lemos \u2013 Advocacia para Neg\u00f3cios","description":"Escrit\u00f3rio de Advocacia","publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"alternateName":"Lemos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lemosadv.com.br\/pb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/lemosadv.com.br\/pb\/#organization","name":"Lemos - Advocacia para neg\u00f3cios","url":"https:\/\/lemosadv.com.br\/pb\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","width":512,"height":512,"caption":"Lemos - Advocacia para neg\u00f3cios"},"image":{"@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","https:\/\/www.instagram.com\/lemosadv_\/","https:\/\/www.linkedin.com\/company\/lemosadvocacia"]},{"@type":"Person","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/9d4d106f4f03dbaa7164e5abe5b03894","name":"Ana Paula Perez","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2cd920fee3d8f82f2cd5a177a17ae7fe3e337f963365959daa6d6db741895c31?s=96&d=mm&r=g","caption":"Ana Paula Perez"},"url":"https:\/\/lemosadv.com.br\/pb\/author\/lemos\/"}]}},"_links":{"self":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/comments?post=525"}],"version-history":[{"count":2,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/525\/revisions"}],"predecessor-version":[{"id":527,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/525\/revisions\/527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/media\/528"}],"wp:attachment":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/media?parent=525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/categories?post=525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/tags?post=525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}