{"id":552,"date":"2024-11-28T12:17:08","date_gmt":"2024-11-28T15:17:08","guid":{"rendered":"https:\/\/lemosadv.com.br\/?p=552"},"modified":"2024-11-28T13:37:57","modified_gmt":"2024-11-28T16:37:57","slug":"a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst","status":"publish","type":"post","link":"https:\/\/lemosadv.com.br\/pb\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\/","title":{"rendered":"A aplica\u00e7\u00e3o da Reforma Trabalhista aos contratos vigentes: Entendimento vinculante do TST"},"content":{"rendered":"<p>Em recente decis\u00e3o proferida em 25 de novembro de 2024, o Tribunal Superior do Trabalho (TST) consolidou entendimento sobre a aplica\u00e7\u00e3o da Reforma Trabalhista (Lei n\u00ba 13.467\/2017), estabelecendo, por meio do julgamento do Incidente de Recursos Repetitivos (IRR) no processo n\u00ba 528-80.2018.5.14.0004, a tese vinculante do Tema 23.<\/p>\n<p>A decis\u00e3o determinou que a reforma se aplica de forma imediata aos contratos de trabalho em vigor, mas somente em rela\u00e7\u00e3o aos fatos ocorridos ap\u00f3s sua entrada em vigor, em 11 de novembro de 2017.<\/p>\n<p><strong>O efeito vinculante da decis\u00e3o \u00e9 de grande relev\u00e2ncia, pois obriga todas as inst\u00e2ncias da Justi\u00e7a do Trabalho a adotar o mesmo entendimento em casos similares, uniformizando a aplica\u00e7\u00e3o da legisla\u00e7\u00e3o trabalhista. A tese fixada esclarece que a nova legisla\u00e7\u00e3o n\u00e3o retroage para alterar direitos j\u00e1 consolidados antes de sua vig\u00eancia, mas regula eventos futuros nos contratos em curso.<\/strong><\/p>\n<p>Essa defini\u00e7\u00e3o vinculante oferece maior seguran\u00e7a jur\u00eddica para empregadores e trabalhadores, ao evitar interpreta\u00e7\u00f5es conflitantes sobre os impactos da reforma em contratos celebrados antes de sua promulga\u00e7\u00e3o. Al\u00e9m disso, a decis\u00e3o reafirma o equil\u00edbrio entre a aplica\u00e7\u00e3o imediata da lei nova e a preserva\u00e7\u00e3o de direitos adquiridos, estabelecendo um marco para julgamentos futuros em todo o pa\u00eds.<\/p>","protected":false},"excerpt":{"rendered":"<p>Em recente decis\u00e3o proferida em 25 de novembro de 2024, o Tribunal Superior do Trabalho (TST) consolidou entendimento sobre a aplica\u00e7\u00e3o da Reforma Trabalhista (Lei [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":553,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[40],"class_list":["post-552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-direito-trabalhista"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A aplica\u00e7\u00e3o da Reforma Trabalhista aos contratos vigentes: Entendimento vinculante do TST &#8211; Lemos - Advocacia para neg\u00f3cios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lemosadv.com.br\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:pb]A aplica\u00e7\u00e3o da Reforma Trabalhista aos contratos vigentes: Entendimento vinculante do TST[:] &#8211; Lemos - Advocacia para neg\u00f3cios\" \/>\n<meta property=\"og:description\" content=\"Em recente decis\u00e3o proferida em 25 de novembro de 2024, o Tribunal Superior do Trabalho (TST) consolidou entendimento sobre a aplica\u00e7\u00e3o da Reforma Trabalhista (Lei [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lemosadv.com.br\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\/\" \/>\n<meta property=\"og:site_name\" content=\"Lemos - Advocacia para neg\u00f3cios\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-28T15:17:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-28T16:37:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/11\/scott-graham-OQMZwNd3ThU-unsplash-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/d596db55770da72ca6d193b9667d8b51\"},\"headline\":\"A aplica\u00e7\u00e3o da Reforma Trabalhista aos contratos vigentes: Entendimento vinculante do TST\",\"datePublished\":\"2024-11-28T15:17:08+00:00\",\"dateModified\":\"2024-11-28T16:37:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\\\/\"},\"wordCount\":232,\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/scott-graham-OQMZwNd3ThU-unsplash-1-scaled.jpg\",\"keywords\":[\"Direito Trabalhista\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\\\/\",\"name\":\"[:pb]A aplica\u00e7\u00e3o da Reforma Trabalhista aos contratos vigentes: Entendimento vinculante do TST[:] &#8211; Lemos - Advocacia para neg\u00f3cios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/scott-graham-OQMZwNd3ThU-unsplash-1-scaled.jpg\",\"datePublished\":\"2024-11-28T15:17:08+00:00\",\"dateModified\":\"2024-11-28T16:37:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lemosadv.com.br\\\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/scott-graham-OQMZwNd3ThU-unsplash-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/scott-graham-OQMZwNd3ThU-unsplash-1-scaled.jpg\",\"width\":2560,\"height\":1709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A aplica\u00e7\u00e3o da Reforma Trabalhista aos contratos vigentes: Entendimento vinculante do TST\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"name\":\"Lemos \u2013 Advocacia para Neg\u00f3cios\",\"description\":\"Escrit\u00f3rio de Advocacia\",\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"alternateName\":\"Lemos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\",\"name\":\"Lemos - Advocacia para neg\u00f3cios\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Lemos - Advocacia para neg\u00f3cios\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/lemosadvocaciaparanegocios\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lemosadv_\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lemosadvocacia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/person\\\/d596db55770da72ca6d193b9667d8b51\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/lemos.letsite.com.br\"],\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:pb]A aplica\u00e7\u00e3o da Reforma Trabalhista aos contratos vigentes: Entendimento vinculante do TST[:] &#8211; Lemos - Advocacia para neg\u00f3cios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lemosadv.com.br\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\/","og_locale":"pt_BR","og_type":"article","og_title":"[:pb]A aplica\u00e7\u00e3o da Reforma Trabalhista aos contratos vigentes: Entendimento vinculante do TST[:] &#8211; Lemos - Advocacia para neg\u00f3cios","og_description":"Em recente decis\u00e3o proferida em 25 de novembro de 2024, o Tribunal Superior do Trabalho (TST) consolidou entendimento sobre a aplica\u00e7\u00e3o da Reforma Trabalhista (Lei [&hellip;]","og_url":"https:\/\/lemosadv.com.br\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\/","og_site_name":"Lemos - Advocacia para neg\u00f3cios","article_publisher":"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","article_published_time":"2024-11-28T15:17:08+00:00","article_modified_time":"2024-11-28T16:37:57+00:00","og_image":[{"width":2560,"height":1709,"url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/11\/scott-graham-OQMZwNd3ThU-unsplash-1-scaled.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lemosadv.com.br\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\/#article","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\/"},"author":{"name":"admin","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/d596db55770da72ca6d193b9667d8b51"},"headline":"A aplica\u00e7\u00e3o da Reforma Trabalhista aos contratos vigentes: Entendimento vinculante do TST","datePublished":"2024-11-28T15:17:08+00:00","dateModified":"2024-11-28T16:37:57+00:00","mainEntityOfPage":{"@id":"https:\/\/lemosadv.com.br\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\/"},"wordCount":232,"publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"image":{"@id":"https:\/\/lemosadv.com.br\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/11\/scott-graham-OQMZwNd3ThU-unsplash-1-scaled.jpg","keywords":["Direito Trabalhista"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/lemosadv.com.br\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\/","url":"https:\/\/lemosadv.com.br\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\/","name":"[:pb]A aplica\u00e7\u00e3o da Reforma Trabalhista aos contratos vigentes: Entendimento vinculante do TST[:] &#8211; Lemos - Advocacia para neg\u00f3cios","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/pb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lemosadv.com.br\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\/#primaryimage"},"image":{"@id":"https:\/\/lemosadv.com.br\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/11\/scott-graham-OQMZwNd3ThU-unsplash-1-scaled.jpg","datePublished":"2024-11-28T15:17:08+00:00","dateModified":"2024-11-28T16:37:57+00:00","breadcrumb":{"@id":"https:\/\/lemosadv.com.br\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lemosadv.com.br\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lemosadv.com.br\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\/#primaryimage","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/11\/scott-graham-OQMZwNd3ThU-unsplash-1-scaled.jpg","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/11\/scott-graham-OQMZwNd3ThU-unsplash-1-scaled.jpg","width":2560,"height":1709},{"@type":"BreadcrumbList","@id":"https:\/\/lemosadv.com.br\/a-aplicacao-da-reforma-trabalhista-aos-contratos-vigentes-entendimento-vinculante-do-tst\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lemosadv.com.br\/pb\/"},{"@type":"ListItem","position":2,"name":"A aplica\u00e7\u00e3o da Reforma Trabalhista aos contratos vigentes: Entendimento vinculante do TST"}]},{"@type":"WebSite","@id":"https:\/\/lemosadv.com.br\/pb\/#website","url":"https:\/\/lemosadv.com.br\/pb\/","name":"Lemos \u2013 Advocacia para Neg\u00f3cios","description":"Escrit\u00f3rio de Advocacia","publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"alternateName":"Lemos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lemosadv.com.br\/pb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/lemosadv.com.br\/pb\/#organization","name":"Lemos - Advocacia para neg\u00f3cios","url":"https:\/\/lemosadv.com.br\/pb\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","width":512,"height":512,"caption":"Lemos - Advocacia para neg\u00f3cios"},"image":{"@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","https:\/\/www.instagram.com\/lemosadv_\/","https:\/\/www.linkedin.com\/company\/lemosadvocacia"]},{"@type":"Person","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/person\/d596db55770da72ca6d193b9667d8b51","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/lemos.letsite.com.br"],"url":"https:\/\/lemosadv.com.br\/pb\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/comments?post=552"}],"version-history":[{"count":2,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/552\/revisions"}],"predecessor-version":[{"id":555,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/posts\/552\/revisions\/555"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/media\/553"}],"wp:attachment":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/media?parent=552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/categories?post=552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/tags?post=552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}