{"id":324,"date":"2024-07-17T12:40:07","date_gmt":"2024-07-17T15:40:07","guid":{"rendered":"https:\/\/lemos.letsite.com.br\/?post_type=profissional&#038;p=324"},"modified":"2026-03-23T11:13:26","modified_gmt":"2026-03-23T14:13:26","slug":"vanessa-sacchi-dias","status":"publish","type":"profissional","link":"https:\/\/lemosadv.com.br\/pb\/profissional\/vanessa-sacchi-dias\/","title":{"rendered":"Vanessa Sacchi Dias"},"content":{"rendered":"<p>Bacharel em Direito pela Universidade Paulista \u2013 UNIP;<br \/>\nP\u00f3s-gradua\u00e7\u00e3o em Direito Processo do Trabalho pelo Centro Universit\u00e1rio Salesiano;<br \/>\nP\u00f3s-gradua\u00e7\u00e3o em Direito Empresarial pela FGV.<\/p>","protected":false},"featured_media":2131,"template":"","tags":[40],"tipo":[6],"alfabeto":[44],"class_list":["post-324","profissional","type-profissional","status-publish","has-post-thumbnail","hentry","tag-direito-trabalhista","tipo-equipe-juridica","alfabeto-v"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vanessa Sacchi Dias &#8211; Lemos - Advocacia para neg\u00f3cios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lemosadv.com.br\/profissional\/vanessa-sacchi-dias\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vanessa Sacchi Dias &#8211; Lemos - Advocacia para neg\u00f3cios\" \/>\n<meta property=\"og:description\" content=\"Bacharel em Direito pela Universidade Paulista \u2013 UNIP; P\u00f3s-gradua\u00e7\u00e3o em Direito Processo do Trabalho pelo Centro Universit\u00e1rio Salesiano; P\u00f3s-gradua\u00e7\u00e3o em Direito Empresarial pela FGV.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lemosadv.com.br\/profissional\/vanessa-sacchi-dias\/\" \/>\n<meta property=\"og:site_name\" content=\"Lemos - Advocacia para neg\u00f3cios\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T14:13:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/7-1-1024x754.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"754\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/profissional\\\/vanessa-sacchi-dias\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/profissional\\\/vanessa-sacchi-dias\\\/\",\"name\":\"Vanessa Sacchi Dias &#8211; Lemos - Advocacia para neg\u00f3cios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/profissional\\\/vanessa-sacchi-dias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/profissional\\\/vanessa-sacchi-dias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/7-1.png\",\"datePublished\":\"2024-07-17T15:40:07+00:00\",\"dateModified\":\"2026-03-23T14:13:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/profissional\\\/vanessa-sacchi-dias\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lemosadv.com.br\\\/profissional\\\/vanessa-sacchi-dias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/profissional\\\/vanessa-sacchi-dias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/7-1.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/7-1.png\",\"width\":2362,\"height\":1739},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/profissional\\\/vanessa-sacchi-dias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vanessa Sacchi Dias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#website\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"name\":\"Lemos \u2013 Advocacia para Neg\u00f3cios\",\"description\":\"Escrit\u00f3rio de Advocacia\",\"publisher\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\"},\"alternateName\":\"Lemos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#organization\",\"name\":\"Lemos - Advocacia para neg\u00f3cios\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/lemosadv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Lemos - Advocacia para neg\u00f3cios\"},\"image\":{\"@id\":\"https:\\\/\\\/lemosadv.com.br\\\/pb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/lemosadvocaciaparanegocios\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lemosadv_\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lemosadvocacia\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vanessa Sacchi Dias &#8211; Lemos - Advocacia para neg\u00f3cios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lemosadv.com.br\/profissional\/vanessa-sacchi-dias\/","og_locale":"pt_BR","og_type":"article","og_title":"Vanessa Sacchi Dias &#8211; Lemos - Advocacia para neg\u00f3cios","og_description":"Bacharel em Direito pela Universidade Paulista \u2013 UNIP; P\u00f3s-gradua\u00e7\u00e3o em Direito Processo do Trabalho pelo Centro Universit\u00e1rio Salesiano; P\u00f3s-gradua\u00e7\u00e3o em Direito Empresarial pela FGV.","og_url":"https:\/\/lemosadv.com.br\/profissional\/vanessa-sacchi-dias\/","og_site_name":"Lemos - Advocacia para neg\u00f3cios","article_publisher":"https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","article_modified_time":"2026-03-23T14:13:26+00:00","og_image":[{"width":1024,"height":754,"url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/7-1-1024x754.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lemosadv.com.br\/profissional\/vanessa-sacchi-dias\/","url":"https:\/\/lemosadv.com.br\/profissional\/vanessa-sacchi-dias\/","name":"Vanessa Sacchi Dias &#8211; Lemos - Advocacia para neg\u00f3cios","isPartOf":{"@id":"https:\/\/lemosadv.com.br\/pb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lemosadv.com.br\/profissional\/vanessa-sacchi-dias\/#primaryimage"},"image":{"@id":"https:\/\/lemosadv.com.br\/profissional\/vanessa-sacchi-dias\/#primaryimage"},"thumbnailUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/7-1.png","datePublished":"2024-07-17T15:40:07+00:00","dateModified":"2026-03-23T14:13:26+00:00","breadcrumb":{"@id":"https:\/\/lemosadv.com.br\/profissional\/vanessa-sacchi-dias\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lemosadv.com.br\/profissional\/vanessa-sacchi-dias\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lemosadv.com.br\/profissional\/vanessa-sacchi-dias\/#primaryimage","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/7-1.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/07\/7-1.png","width":2362,"height":1739},{"@type":"BreadcrumbList","@id":"https:\/\/lemosadv.com.br\/profissional\/vanessa-sacchi-dias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lemosadv.com.br\/pb\/"},{"@type":"ListItem","position":2,"name":"Vanessa Sacchi Dias"}]},{"@type":"WebSite","@id":"https:\/\/lemosadv.com.br\/pb\/#website","url":"https:\/\/lemosadv.com.br\/pb\/","name":"Lemos \u2013 Advocacia para Neg\u00f3cios","description":"Escrit\u00f3rio de Advocacia","publisher":{"@id":"https:\/\/lemosadv.com.br\/pb\/#organization"},"alternateName":"Lemos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lemosadv.com.br\/pb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/lemosadv.com.br\/pb\/#organization","name":"Lemos - Advocacia para neg\u00f3cios","url":"https:\/\/lemosadv.com.br\/pb\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/","url":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","contentUrl":"https:\/\/lemosadv.com.br\/wp-content\/uploads\/2024\/06\/favicon.png","width":512,"height":512,"caption":"Lemos - Advocacia para neg\u00f3cios"},"image":{"@id":"https:\/\/lemosadv.com.br\/pb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/lemosadvocaciaparanegocios\/","https:\/\/www.instagram.com\/lemosadv_\/","https:\/\/www.linkedin.com\/company\/lemosadvocacia"]}]}},"_links":{"self":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/profissional\/324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/profissional"}],"about":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/types\/profissional"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/media\/2131"}],"wp:attachment":[{"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/media?parent=324"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/tags?post=324"},{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/tipo?post=324"},{"taxonomy":"alfabeto","embeddable":true,"href":"https:\/\/lemosadv.com.br\/pb\/wp-json\/wp\/v2\/alfabeto?post=324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}